{"id":12810,"date":"2014-07-19T02:41:44","date_gmt":"2014-07-19T02:41:44","guid":{"rendered":"http:\/\/www.newmessage.org\/?page_id=12810"},"modified":"2019-10-30T23:17:28","modified_gmt":"2019-10-30T23:17:28","slug":"society","status":"publish","type":"page","link":"https:\/\/www.v6.newmessage.org\/fr\/worldwide-community\/society","title":{"rendered":"La Society"},"content":{"rendered":"<div class=\"floater-right\">\n<p><!-- <a href=\"https:\/\/www.newmessage.org\/the-messenger-and-the-members-of-the-society\"><img loading=\"lazy\" decoding=\"async\" class=\"imgborder text-align-right alignnone size-medium\" src=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2015\/08\/Society-FINAL-group-photo-8-300x187.jpg\" alt=\"From upper left: Robert Busbey, Patricia Summers, Marshall Vian Summers, Reed Summers, Carol Coffey, Will Burrows, Tyyne Andrews, Darlene Mitchell, Ayesha Summers, Jeanine Butler, Ellen Mitchell, Ana Burrows. Photo taken: Sept, 2015\" width=\"300\" height=\"187\" \/><\/a> --><\/p>\n\n<div class=\"tabgroup \"><ul class=\"tabs\"><li><a href=\"#tabs-1\">Table des mati\u00e8res<\/a><\/li><\/ul>\n <div id=\"tabs-1\"><br \/>\n<a href=\"#whatissociety\">Qu&rsquo;est-ce que la <em>Society <\/em>?<\/a><br \/>\n<a href=\"#ourwork\">Notre \u0152uvre<\/a><br \/>\n<a href=\"#ourmission\">La formulation de notre mission<\/a><br \/>\n<a href=\"#strategic\">Objectifs strat\u00e9giques<\/a><br \/>\n<a href=\"#leadership\">La direction<\/a><br \/>\n<a href=\"#members\">\u00c0 propos des membres de la <em>Society<\/em><\/a><br \/>\n<a href=\"#story\">L&rsquo;histoire des membres<\/a><br \/>\n<a href=\"#core\">\u00c0 propos des <em>core-assistants<\/em><\/a><br \/>\n<a href=\"#volunteers\">\u00c0 propos des volontaires<\/a><\/div>\n\t\t\t\t<div align=\"right\">\n\t\t\t<div class=\"fb-like\" data-href=\"\" data-layout=\"button_count\" data-action=\"like\" data-show-faces=\"false\" data-share=\"false\"><\/div>\n\t\t\t<div class=\"fb-share-button\" data-layout=\"button_count\"> <\/div>\n\t\t\t<div class=\"fb_iframe_widget\"><a href=\"https:\/\/twitter.com\/godsnewmessage?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-show-count=\"false\">Follow @godsnewmessage<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n\t\t\t<\/div> <\/div> \n\n<\/div>\n<p><a name=\"whatissociety\"><\/a><\/p>\n<h2>Qu&rsquo;est-ce que la Society ?<\/h2>\n<p>La <em>Society for the New Message from God <\/em>(la Soci\u00e9t\u00e9 pour le Nouveau Message de Dieu) est une organisation religieuse \u00e0 but non lucratif dont la mission est de pr\u00e9server, de prot\u00e9ger et de pr\u00e9senter le Nouveau Message de Dieu dans le monde. La <em>Society<\/em> n&rsquo;est affili\u00e9e \u00e0 aucun corpus religieux. Elle est ind\u00e9pendante et soutenue financi\u00e8rement par des <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/society\/soutenir-le-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\">dons<\/a> provenant des \u00e9tudiants du Nouveau Message du monde entier, et ne re\u00e7oit ni subvention ni revenu d&rsquo;aucun gouvernement ni d&rsquo;aucune organisation religieuse.<\/p>\n<p>La <em>Society<\/em> fut fond\u00e9e en 1992 par <a href=\"http:\/\/www.nouveaumessagededieu.org\/messager-de-dieu\" target=\"_blank\" rel=\"noopener noreferrer\">le Messager Marshall Vian Summers<\/a> qui vit le besoin d&rsquo;une organisation et d&rsquo;un noyau de personnes d\u00e9vou\u00e9es qui puissent \u00e9pauler la mission du Messager durant son vivant et au-del\u00e0, prot\u00e9geant ainsi la R\u00e9v\u00e9lation et en pr\u00e9servant la puret\u00e9 aussi loin que possible dans l&rsquo;avenir.<\/p>\n<p>Depuis ce jour, La <em>Society<\/em> a partag\u00e9 le fardeau du Messager, se tenant \u00e0 ses c\u00f4t\u00e9s, \u00e9tant le t\u00e9moin du processus de R\u00e9v\u00e9lation et entreprenant cette grande t\u00e2che d&rsquo;apporter une Nouvelle R\u00e9v\u00e9lation de Dieu \u00e0 l&rsquo;humanit\u00e9.<\/p>\n<p>La <em>Society<\/em> est form\u00e9e de onze membres et de neuf c<em>ore assistants <\/em>(assistants principaux) qui chacun ont choisi de r\u00e9pondre \u00e0 l&rsquo;appel qu&rsquo;ils ont ressenti pour assister le Messager et faire progresser l&rsquo;\u00e9mergence du Nouveau Message dans le monde. La <em>Society<\/em> est de plus assist\u00e9e et soutenue par des volontaires d\u00e9vou\u00e9s vivant dans diff\u00e9rents pays et apportant leur service selon de nombreuses capacit\u00e9s diff\u00e9rentes.<\/p>\n<p>La <em>Society<\/em> suit les directives de celui qui dirige le Nouveau Message, Marshall Vian Summers. Assistant Marshall Vian Summers, Reed Summers est le directeur de la <em>Society<\/em>, et il coordonne l&rsquo;\u00e9quipe de direction qui veille sur les d\u00e9partements de l&rsquo;organisation.<br \/>\n<a name=\"ourwork\"><\/a><\/p>\n<h2>Notre \u0152uvre<\/h2>\n<p class=\"alignnone\"><a href=\"https:\/\/www.newmessage.org\/organizational-chart-of-the-society\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"\/wp-content\/uploads\/2015\/04\/org-chart-may-2015.jpg\" alt=\"\" width=\"382\" height=\"295\" \/><\/a>La mission de la <i>Society<\/i> est de porter le Nouveau Message de Dieu dans le monde pour que chacun puisse y avoir acc\u00e8s, et afin que l\u2019humanit\u00e9 puisse trouver son terrain d\u2019entente, pr\u00e9server la Terre, pr\u00e9server sa libert\u00e9 et faire avancer sa civilisation, alors m\u00eame que nous arrivons au seuil de changements sans pr\u00e9c\u00e9dent.<\/p>\n<p>Le travail de la <em>Society<\/em> est d\u00e9di\u00e9 \u00e0 l&rsquo;avancement de la mission du Message et du Messager &#8211; une mission \u00e9tablie \u00e0 l&rsquo;origine par <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/volume-2\/la-spiritualite-de-la-grande-communaute\/1-quest-ce-que-dieu\" target=\"_blank\" rel=\"noopener noreferrer\">Dieu<\/a> et <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#aa\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;Assembl\u00e9e Ang\u00e9lique<\/a>. Cette mission est profond\u00e9ment li\u00e9e \u00e0 l&rsquo;\u00e9volution et \u00e0 la destin\u00e9e de notre monde et est une extension directe d&rsquo;un Plan Divin destin\u00e9 \u00e0 servir notre monde \u00e0 cette \u00e9poque cruciale de l&rsquo;histoire humaine.<\/p>\n<p>Depuis le commencement des temps et la cr\u00e9ation de l&rsquo;univers manifest\u00e9, Dieu et la Pr\u00e9sence Ang\u00e9lique ont d\u00e9velopp\u00e9 un Plan pour gu\u00e9rir <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/volume-1\/le-dieu-un\/la-separation\" target=\"_blank\" rel=\"noopener noreferrer\">la S\u00e9paration<\/a> et sauver ceux qui sont s\u00e9par\u00e9s gr\u00e2ce \u00e0 la <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#kn\" target=\"_blank\" rel=\"noopener noreferrer\">Connaissance<\/a>, \u00e0 la fois dans notre monde et partout dans <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#gc\" target=\"_blank\" rel=\"noopener noreferrer\">la Grande Communaut\u00e9<\/a> de vie intelligente dans l&rsquo;univers.<\/p>\n<p>La <em>Society<\/em> est d\u00e9vou\u00e9e au service de cette grande mission et de ce grand Plan de Dieu. Aujourd&rsquo;hui, notre travail prioritaire est de recevoir, de pr\u00e9server, de prot\u00e9ger et de pr\u00e9senter le Nouveau Message de Dieu dans le monde. Nous nous effor\u00e7ons de faire cela par la publication de livres, en soutenant le processus de traduction international, en d\u00e9veloppant des sites web, des <a href=\"https:\/\/www.newmessage.org\/forum\" target=\"_blank\" rel=\"noopener noreferrer\">forums<\/a> et de nombreux autres environnements en ligne, apportant ainsi une \u00e9ducation \u00e0 <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/a-propos-de-la-communaute-mondiale\" target=\"_blank\" rel=\"noopener noreferrer\">la communaut\u00e9 mondiale<\/a>, par l&rsquo;interm\u00e9diaire d&rsquo;\u00e9v\u00e9nements, de <em>broadcasts<\/em> (\u00e9v\u00e9nements film\u00e9s et diffus\u00e9s en ligne en direct), des <em><a href=\"https:\/\/www.newmessage.org\/encampment\" target=\"_blank\" rel=\"noopener noreferrer\">Encampments<\/a><\/em> (rassemblements annuels des \u00e9tudiants) et de la <a href=\"http:\/\/www.nouveaumessagededieu.org\/ecole-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Free School<\/em> (l&rsquo;\u00e9cole) du Nouveau Message.<\/a><\/p>\n<p>Gr\u00e2ce \u00e0 cela, l&rsquo;appel et la communication de Dieu peuvent atteindre le c\u0153ur des gens un peu partout, \u00e9veillant le pouvoir de la <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms\" target=\"_blank\" rel=\"noopener noreferrer\">Connaissance<\/a> dans le monde afin que chacun puisse d\u00e9couvrir sa contribution unique \u00e0 cette \u00e9poque dont les besoins, les changements et les opportunit\u00e9s ne font que s&rsquo;accro\u00eetre.<\/p>\n<p>Il s\u2019agit pourtant d\u2019une responsabilit\u00e9 qui d\u00e9passe de loin ce que nous pouvons faire seuls et qui requiert le soutien et l\u2019assistance de nombreuses personnes. Le livre que vous tenez dans les mains, le site internet qui vous informe et vous inspire, le <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/society\/le-sanctuaire-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\">Sanctuaire<\/a> de la Grande Communaut\u00e9 qui accueille les<a href=\"https:\/\/www.newmessage.org\/worldwide-community\/events\" target=\"_blank\" rel=\"noopener noreferrer\"> \u00e9v\u00e9nements<\/a> du Nouveau Message, le bureau qui maintient cette organisation, sont tous les fruits des contributions de nombreuses personnes\u00a0: du temps, de l\u2019\u00e9nergie, mais aussi de l\u2019argent, car toute organisation humaine, m\u00eame au service de Dieu, en a besoin pour fonctionner dans le monde\u2026 Et gr\u00e2ce aux contributions financi\u00e8res, les portes du <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/society\/le-sanctuaire-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\">Sanctuaire<\/a> de la Grande Communaut\u00e9 et la <a href=\"http:\/\/www.nouveaumessagededieu.org\/ecole-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Free School<\/em> du Nouveau Message<\/a> sont ouvertes \u00e0 tous gratuitement, et un nombre croissant des volumes et des livres du Nouveau Message sont en libre consultation en ligne.\u00a0Vous, qui \u00eates peut-\u00eatre parmi les premiers \u00e0 recevoir et \u00e0 vivre le Nouveau Message de Dieu, pouvez vous joindre aux autres en apportant votre contribution effective \u00e0 cette mission vitale.<br \/>\n<a name=\"ourmission\"><\/a><\/p>\n<h2>La formulation de notre mission<\/h2>\n<ol>\n<li>Apporter <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\" target=\"_blank\" rel=\"noopener noreferrer\">le Nouveau Message de Dieu<\/a> \u00e0 l&rsquo;humanit\u00e9 sous sa forme pure.<\/li>\n<li>Porter la nouvelle de l&rsquo;existence du <a href=\"http:\/\/www.nouveaumessagededieu.org\/messager-de-dieu\" target=\"_blank\" rel=\"noopener noreferrer\">Messager<\/a> et de sa pr\u00e9sence dans le monde aux gens du monde entier.<\/li>\n<li>Soutenir l&rsquo;\u00e9mergence de la <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#kn\" target=\"_blank\" rel=\"noopener noreferrer\">Connaissance<\/a> dans la vie des gens o\u00f9 qu&rsquo;ils se trouvent, par l&rsquo;\u00e9ducation et le chemin de d\u00e9veloppement contenus dans le Nouveau Message.<\/li>\n<li>Promouvoir la conscience et la pr\u00e9paration relatives aux <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#gwc\" target=\"_blank\" rel=\"noopener noreferrer\">Grandes Vagues de changement<\/a> et \u00e0 l&rsquo;\u00e9mergence de l\u2019humanit\u00e9 dans la <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#gc\" target=\"_blank\" rel=\"noopener noreferrer\">Grande Communaut\u00e9<\/a> de vie intelligente dans l&rsquo;univers.<\/li>\n<li>Encourager l&rsquo;unit\u00e9 et la tol\u00e9rance entre les religions du monde, comme la Nouvelle R\u00e9v\u00e9lation de Dieu pour notre temps nous y invite.<\/li>\n<li>Apporter son soutien au Messager, alors que celui-ci continue \u00e0 recevoir la Nouvelle R\u00e9v\u00e9lation de Dieu pour le monde.<\/li>\n<li>\u00c9tablir <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/a-propos-de-la-communaute-mondiale\" target=\"_blank\" rel=\"noopener noreferrer\">la Communaut\u00e9 Mondiale du Nouveau Message<\/a> pour apprendre, vivre et soutenir le Nouveau Message en alignement avec le Messager et la <em>Society<\/em>.<\/li>\n<li>B\u00e2tir une structure bien organis\u00e9e capable de porter le Nouveau Message de Dieu dans le monde et dans l&rsquo;avenir.<\/li>\n<\/ol>\n<p><a name=\"strategic\"><\/a><\/p>\n<h2>Objectifs strat\u00e9giques<\/h2>\n<ol>\n<li>\u00c9tablir la conscience et la tradition spirituelles du Nouveau Message dans le monde.<\/li>\n<li>Atteindre des millions de personnes dans le monde entier avec les enseignements et la proclamation du Nouveau Message.<\/li>\n<li>Pr\u00e9senter le texte et l&rsquo;audio du <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\" target=\"_blank\" rel=\"noopener noreferrer\">Testament du Nouveau Message de Dieu<\/a>.<\/li>\n<li>Rendre accessible la grande profondeur et la grande port\u00e9e du Nouveau Message par l&rsquo;interm\u00e9diaire de livres, de sites web et de traductions.<\/li>\n<li>Pr\u00e9senter la <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#vr\" target=\"_blank\" rel=\"noopener noreferrer\">Voix de la R\u00e9v\u00e9lation<\/a> au monde sous sa forme audio originale.<\/li>\n<li>Publier les enseignements du Messager \u00e0 la fois sous forme audio et \u00e9crite.<\/li>\n<li>\u00c9tablir la vision du Messager du chemin d&rsquo;apprentissage et de vie du Nouveau Message.<\/li>\n<li>Offrir l&rsquo;opportunit\u00e9 pour les gens du monde entier de s&rsquo;engager avec la R\u00e9v\u00e9lation et avec leur propre nature profonde et leur propre appel dans la vie gr\u00e2ce \u00e0 la <a href=\"http:\/\/www.nouveaumessagededieu.org\/ecole-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Free School<\/em> du Nouveau Message<\/a>.<\/li>\n<li>B\u00e2tir une stabilit\u00e9 et une r\u00e9silience organisationnelle pour pouvoir faire face \u00e0 la r\u00e9ponse du monde au Nouveau Message et \u00e0 sa proclamation.<\/li>\n<\/ol>\n<p><a name=\"leadership\"><\/a><\/p>\n<h2>\u00c0 propos de la direction du Nouveau Message<\/h2>\n<p><a name=\"mvs\"><\/a><\/p>\n<h3 style=\"text-align: center;\">Marshall Vian Summers<\/h3>\n<h4 style=\"text-align: center;\"><span style=\"color: #808080;\">en tant que Messager, Marshall Vian Summers dirige le Nouveau Message de Dieu<\/span><\/h4>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/2015\/08\/DSC_0146-copy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"imgborder alignnone size-large\" src=\"\/wp-content\/uploads\/2015\/08\/DSC_0146-copy-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/p>\n<p>Marshall Vian Summers est le Messager du Nouveau Message de Dieu. Il a \u00e9t\u00e9 s\u00e9lectionn\u00e9 et pr\u00e9par\u00e9 par <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms#aa\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;Assembl\u00e9e Ang\u00e9lique<\/a> avant cette vie sur Terre pour servir dans ce r\u00f4le de Messager pour la Nouvelle R\u00e9v\u00e9lation et il a \u00e0 pr\u00e9sent re\u00e7u la r\u00e9v\u00e9lation la plus vaste et la plus compl\u00e8te jamais donn\u00e9e \u00e0 l&rsquo;humanit\u00e9.<\/p>\n<p>Marshall est le fondateur de la <em>Society<\/em>, qu&rsquo;il a mise en place en 1992 pour pr\u00e9server et pr\u00e9senter le Nouveau Message de Dieu et <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/a-propos-de-la-communaute-mondiale\" target=\"_blank\" rel=\"noopener noreferrer\">la communaut\u00e9 mondiale du Nouveau Message<\/a>. Sa femme Patricia Summers lui succ\u00e8dera dans son r\u00f4le de direction.<\/p>\n<p>Aujourd&rsquo;hui, le Messager continue \u00e0 recevoir le Nouveau Message de Dieu pour ces temps et pour les temps \u00e0 venir. Il est de plus engag\u00e9 dans la diffusion de sa proclamation et de son message essentiel pour le monde. Il enregistre \u00e9galement un vaste h\u00e9ritage d&rsquo;enseignements, de directives et de clarifications pour aider les \u00e9tudiants \u00e0 apprendre et \u00e0 vivre le Nouveau Message. Enfin, il travaille au projet historique de compilation de la totalit\u00e9 -soit plus de 9000 pages- de la R\u00e9v\u00e9lation en un nouveau testament pour l&rsquo;humanit\u00e9.<br \/>\n<a name=\"rs\"><\/a><\/p>\n<h3 style=\"text-align: center;\">Reed Summers<\/h3>\n<h4 style=\"text-align: center;\">enseignant et repr\u00e9sentant du Nouveau Message<\/h4>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2014\/07\/Reed-Summers-New-Message-from-God.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"imgborder alignright size-medium\" src=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2014\/07\/Reed-Summers-New-Message-from-God-300x282.jpg\" alt=\"\" width=\"300\" height=\"282\" \/><\/a><\/p>\n<p>N\u00e9 dans la tradition du Nouveau Message, en tant que fils du Messager, Reed Summers est un membre de la <em>Society<\/em> et dirige actuellement sa mission de diffusion et d&rsquo;\u00e9ducation. Il apporte \u00e9galement enseignement et direction \u00e0 <a href=\"http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/a-propos-de-la-communaute-mondiale\" target=\"_blank\" rel=\"noopener noreferrer\">la Communaut\u00e9 Mondiale<\/a> des \u00e9tudiants et est le repr\u00e9sentant public principal du Messager.<\/p>\n<p>Reed Summers a rejoint le Messager et la <em>Society<\/em> en 2004, \u00e0 l&rsquo;\u00e2ge de 20 ans. Dans les ann\u00e9es qui ont suivi, il a pris part \u00e0 la mission du Messager dans un large panel d&rsquo;activit\u00e9s : cr\u00e9er le design des sites web, des couvertures de livres et du mat\u00e9riel de diffusion du Nouveau Message; \u00e9crire, parler et enseigner pour la <em>Free School<\/em> du Nouveau Message; coordonner les nombreux voyages du Messager dans le monde; et, aux c\u00f4t\u00e9s de Patricia Summers, d\u00e9velopper le programme de la <em><a href=\"http:\/\/www.nouveaumessagededieu.org\/ecole-du-nouveau-message\" target=\"_blank\" rel=\"noopener noreferrer\">Free School<\/a><\/em> du Nouveau Message, de m\u00eame que les <em>broadcasts<\/em>, les <em><a href=\"https:\/\/www.newmessage.org\/events\" target=\"_blank\" rel=\"noopener noreferrer\">Veill\u00e9es<\/a><\/em> et les rassemblements mondiaux (<em><a href=\"https:\/\/www.newmessage.org\/encampment\" target=\"_blank\" rel=\"noopener noreferrer\">Encampments<\/a><\/em>) du Nouveau Message.<br \/>\n<a name=\"ps\"><\/a><\/p>\n<h3 style=\"text-align: center;\">Patricia Summers<\/h3>\n<h4 style=\"text-align: center;\">enseignante et repr\u00e9sentante du Nouveau Message<\/h4>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2014\/07\/Patricia-Summers-New-Message-from-God.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"imgborder alignright size-medium\" src=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2014\/07\/Patricia-Summers-New-Message-from-God-293x300.jpg\" alt=\"\" width=\"293\" height=\"300\" \/><\/a><\/p>\n<p>Patricia est aux c\u00f4t\u00e9s de Marshall depuis 1983, pratiquement 10 ans avant la cr\u00e9ation de la <em>Society<\/em>. Depuis les tous premiers jours de la R\u00e9v\u00e9lation, elle assiste \u00e9troitement le Messager dans son long voyage consistant \u00e0 recevoir la R\u00e9v\u00e9lation du Nouveau Message, \u00e9tant toujours \u00e0 ses c\u00f4t\u00e9s et l&rsquo;aidant \u00e0 porter le poids grandissant de ses responsabilit\u00e9s et de son r\u00f4le.<\/p>\n<p>Patricia est membre de la <em>Society<\/em>, et, durant trois d\u00e9cennies, elle a aussi aid\u00e9 \u00e0 construire cette organisation, la guidant pour traverser de nombreux d\u00e9fis pour qu&rsquo;elle puisse arriver l\u00e0 o\u00f9 elle est aujourd&rsquo;hui. Elle travaille aujourd&rsquo;hui avec Reed et Marshall Vian Summers pour diriger la <em>Society<\/em>, pr\u00e9parer les livres de R\u00e9v\u00e9lation et pour pr\u00e9senter le Nouveau Message de Dieu au monde. En plus de cela, elle est l&rsquo;enseignante principale du Nouveau Message, avec son fils Reed, offrant une sagesse, une inspiration et une direction essentielles \u00e0 la Communaut\u00e9 Mondiale des \u00e9tudiants de la R\u00e9v\u00e9lation.<br \/>\n<a name=\"members\"><\/a><\/p>\n<h3>\u00c0 propos des membres de la <em>Society<\/em><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"imgborder alignright wp-image-29247 size-medium\" src=\"https:\/\/www.newmessage.org\/fr\/wp-content\/uploads\/sites\/38\/2019\/10\/Society-2017-600x381-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.v6.newmessage.org\/fr\/wp-content\/uploads\/sites\/38\/2019\/10\/Society-2017-600x381-300x191.jpg 300w, https:\/\/www.v6.newmessage.org\/fr\/wp-content\/uploads\/sites\/38\/2019\/10\/Society-2017-600x381.jpg 600w, https:\/\/www.v6.newmessage.org\/fr\/wp-content\/uploads\/sites\/38\/2019\/10\/Society-2017-600x381-500x318.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Marshall Vian Summers et <a href=\"https:\/\/www.newmessage.org\/the-messenger-and-the-members-of-the-society\" target=\"_blank\" rel=\"noopener noreferrer\">les membres de la <em>Society for the New Message from God<\/em><\/a> ont re\u00e7u l&rsquo;immense responsabilit\u00e9 d&rsquo;apporter le Nouveau Message dans le monde. Pour les dix membres de la <em>Society<\/em>, c&rsquo;est \u00e0 la fois un fardeau et une b\u00e9n\u00e9diction et ils s&rsquo;impliquent enti\u00e8rement dans ce grand service \u00e0 l&rsquo;humanit\u00e9.<\/p>\n<p>Les membres de la <em>Society<\/em> sont les intendants et les gardiens de la Parole et du Son Divins du Nouveau Message. Il ont \u00e9t\u00e9 charg\u00e9s de ce r\u00f4le par la Source du Nouveau Message &#8211; prot\u00e9ger, pr\u00e9server et pr\u00e9senter cette Nouvelle R\u00e9v\u00e9lation et la servir avec d\u00e9vouement. Ainsi \u0153uvrent-ils pour veiller \u00e0 la puret\u00e9 du Nouveau Message &#8211; ses publications, ses textes, ses \u00e9v\u00e9nements audios, vid\u00e9os et publics.<\/p>\n<p>La<em> Society<\/em> est engag\u00e9e dans un large panel de responsabilit\u00e9s pratiques li\u00e9es \u00e0 la mission de pr\u00e9servation et de proclamation du Nouveau Message et au soutien du d\u00e9veloppement de la Communaut\u00e9 Mondiale des \u00e9tudiants. Pour ce faire, les membres de la <em>Society <\/em>doivent g\u00e9rer un grand nombre d&rsquo;\u00e9quipes et de projets essentiels et coordonner le travail des c<em>ore assistants<\/em> et des volontaires qui assistent l&rsquo;organisation.<\/p>\n<p>Les membres de la <em>Society <\/em>ne prennent en revanche pas une position de conseillers, de guides ou d&rsquo;enseignants religieux. Ils ne sont pas engag\u00e9s dans l&rsquo;enseignement du Nouveau Message ou dans l&rsquo;\u00e9tablissement d&rsquo;une interpr\u00e9tation des textes. Leur r\u00f4le est plut\u00f4t d&rsquo;apporter leur soutien au travail essentiel de l&rsquo;organisation, ainsi qu&rsquo;au Messager et aux enseignants du Nouveau Message qui apportent un chemin \u00e9ducatif et de l&rsquo;inspiration \u00e0 tous ceux qui cherchent \u00e0 apprendre et \u00e0 vivre la R\u00e9v\u00e9lation.<\/p>\n<p>Il y a \u00e0 ce jour dix membres de la <em>Society<\/em> : <em><strong>Tyyne Andrews, Will Burrows, Robert Busbey, Jeanine Butler, Carol Coffey, Darlene Mitchell, Ellen Mitchell, Ayesha Summers, Reed Summers and Patricia Summers<\/strong><\/em><br \/>\n<a name=\"story\"><\/a><\/p>\n<h3>L&rsquo;histoire des membres de la <em>Society<\/em><\/h3>\n<p>Chaque R\u00e9v\u00e9lation donn\u00e9e par le Cr\u00e9ateur dans l&rsquo;histoire \u00e0 sa propre histoire &#8211; l&rsquo;histoire de sa r\u00e9ception, l&rsquo;histoire de son <a href=\"http:\/\/www.nouveaumessagededieu.org\/messager-de-dieu\/qui-est-marshallviansummers\" target=\"_blank\" rel=\"noopener noreferrer\">Messager<\/a> et l&rsquo;histoire des toutes premi\u00e8res communaut\u00e9s d&rsquo;individus qui se sont rassembl\u00e9es pour soutenir le Messager et pour aider \u00e0 apporter la R\u00e9v\u00e9lation de Dieu au monde.<\/p>\n<p>L&rsquo;histoire de la Nouvelle R\u00e9v\u00e9lation de Dieu se d\u00e9ploie sous nos yeux, autour du Messager, autour de la <em>Society<\/em> &#8211; les petits cercles d&rsquo;individus qui se sont rassembl\u00e9s pour le soutenir &#8211; et la Communaut\u00e9 Mondiale grandissante des \u00e9tudiants. C&rsquo;est une histoire dont les d\u00e9buts sont humbles et dont l&rsquo;\u00e9criture se poursuit.<\/p>\n<p>En 1992, alors engag\u00e9 dans le processus de R\u00e9v\u00e9lation depuis 10 ans, le Messager a mis en place l&rsquo;organisation de la <em>Society<\/em>, m\u00eame si \u00e0 cette \u00e9poque il n&rsquo;y avait alors que tr\u00e8s peu de personnes pr\u00e9sentes \u00e0 ses c\u00f4t\u00e9s pour y prendre part.<\/p>\n<p>Dans les ann\u00e9es qui ont suivi, les membres actuels de la <em>Society<\/em> sont venus trouver la R\u00e9v\u00e9lation et ont finalement pris leur place \u00e0 son service. Chacun d&rsquo;entre eux a sa propre histoire.<\/p>\n<p>Bien que vivant dans des situations, des circonstances et des endroits diff\u00e9rents, chacun d&rsquo;eux a rencontr\u00e9 la R\u00e9v\u00e9lation ou le Messager, et a alors commenc\u00e9 \u00e0 r\u00e9pondre \u00e0 une forme de reconnaissance et \u00e0 un sentiment d&rsquo;appel, faisant les premiers pas vers une vie de service, sans m\u00eame savoir o\u00f9 ces pas le (ou la) m\u00e8neraient ou ce qu&rsquo;ils signifieraient.<\/p>\n<p>Ainsi arriv\u00e8rent-ils, gagnant la libert\u00e9 de trouver leur chemin, l&rsquo;un apr\u00e8s l&rsquo;autre, chaque membre faisant face \u00e0 des d\u00e9fis et \u00e0 de l&rsquo;adversit\u00e9, mais chacun sachant la n\u00e9cessit\u00e9 de venir, de prendre une position de service vis-\u00e0-vis de cette R\u00e9v\u00e9lation en train d&rsquo;\u00e9merger et de cet homme qui la recevait. Cela a demand\u00e9 le d\u00e9veloppement d&rsquo;une plus grande force et d&rsquo;une plus grande stabilit\u00e9, \u00e0 la fois int\u00e9rieures et ext\u00e9rieures, \u00e0 mesure qu&rsquo;ils commen\u00e7aient \u00e0 partager le fardeau du Messager.<\/p>\n<p>Durant des ann\u00e9es de service, ils ont emprunt\u00e9 une route difficile avec le Messager, conservant une d\u00e9votion et un engagement profonds envers lui et sa mission, le lib\u00e9rant afin qu&rsquo;il puisse faire ce que lui seul pouvait faire, se tenant \u00e0 ses c\u00f4t\u00e9s et \u00e9tant l\u00e0 pour lui, peu importe les difficult\u00e9s ou les d\u00e9fis qui se pr\u00e9sentaient.<\/p>\n<p>Il continuent aujourd&rsquo;hui \u00e0 r\u00e9pondre \u00e0 leur sentiment d&rsquo;appel et de responsabilit\u00e9, cherchant \u00e0 accomplir un plus grand service, \u00e0 relever de plus grands d\u00e9fis encore, et voyant leur vies et leur r\u00f4les se pr\u00e9ciser et se red\u00e9finir au service de cette grande mission. Tout ceci afin que le Nouveau Message de Dieu puisse atteindre le monde dans le temps disponible qui reste, apportant une sagesse et une inspiration rarement vues dans ce monde et appelant <a href=\"http:\/\/www.nouveaumessagededieu.org\/le-message\/important-terms\" target=\"_blank\" rel=\"noopener noreferrer\">la Connaissance<\/a> au c\u0153ur de la famille humaine, pour que ce pouvoir spirituel puisse \u00e9merger et guider l&rsquo;humanit\u00e9 en ces temps de grands besoins.<\/p>\n<p>Et pourtant, comment ce petit groupe de gens pourrait-il accomplir cela? Comment peuvent-ils accomplir cette mission? Ce sont des questions avec lesquelles ils vivent.<\/p>\n<p>\u00c0 pr\u00e9sent, d&rsquo;autres personnes commencent \u00e0 r\u00e9pondre \u00e0 leur propre sentiment d&rsquo;appel pour assister la<em> Society<\/em> dans cette grande entreprise. Les <em>core assistants<\/em> et les nombreux volontaires assistent d\u00e9sormais la <em>Society<\/em> et prennent en charge des r\u00f4les et des responsabilit\u00e9 vitales qui permettent \u00e0 cette mission d&rsquo;avancer et de grandir.<\/p>\n<p>L&rsquo;histoire de la jeune communaut\u00e9 de la R\u00e9v\u00e9lation continue \u00e0 se d\u00e9ployer \u00e0 mesure que des individus inspir\u00e9s partout dans le monde r\u00e9pondent \u00e0 la Nouvelle R\u00e9v\u00e9lation de Dieu et prennent leur place de service, \u00e0 la fois dans le monde et en soutien direct \u00e0 la mission du Message et du Messager.<br \/>\n<a name=\"core\"><\/a><\/p>\n<h3>\u00c0 propos des <em>core assistants<\/em> de la <em>Society<\/em><\/h3>\n<p>Les <em>core assistants (assistants principaux)<\/em> de la <em>Society<\/em> sont un \u00e9l\u00e9ment vital de la mission du Nouveau Message de Dieu. Les <em>core assistants<\/em> sont des individus qui ressentent un appel personnel pour servir et faire progresser la mission du Message et du Messager et pour aider la <em>Society<\/em> \u00e0 mener \u00e0 bien cette mission dans le monde. Ils ont fait de cela une priorit\u00e9 de leur vie, fortifiant leurs vies int\u00e9rieures et ext\u00e9rieures suffisamment pour tenir et faire progresser des domaines cl\u00e9s du travail de la <em>Society<\/em> et pour maintenir cela dans le temps. C&rsquo;est une v\u00e9ritable d\u00e9monstration de service authentique.<\/p>\n<p>Il y a actuellement treize\u00a0<em>core assistants<\/em>, dans cinq pays, qui aident la <em>Society<\/em>.<br \/>\n<a name=\"volunteers\"><\/a><\/p>\n<h3>\u00c0 propos des volontaires assistant la <em>Society<\/em><\/h3>\n<p>Les volontaires assistant la <em>Society<\/em> apportent un service crucial pour l&rsquo;avancement de nombreux aspects du travail et de la mission de la <em>Society<\/em>. Les volontaires sont des \u00e9tudiants de la Communaut\u00e9 Mondiale situ\u00e9s un peu partout dans le monde qui sont en mesure d&rsquo;offrir leur temps, leurs comp\u00e9tences et leur disponibilit\u00e9 pour remplir des t\u00e2ches sp\u00e9cifiques, apporter leur aide \u00e0 des projets et collaborer dans les \u00e9quipes et les d\u00e9partements de l&rsquo;organisation. Cette forme de service compl\u00e9mente leur \u00e9tude et leur travail de diffusion du Nouveau Message dans le monde et est un soutien vital au travail et \u00e0 la mission de la <em>Society<\/em> et du Messager.<\/p>\n<p>Il y a actuellement 84 volontaires dans 28 pays assistant la <em>Society<\/em>.<\/p>\n<hr \/>\n<a class='simple_button_link ' style='background-color: #4f8fd6' href='http:\/\/www.nouveaumessagededieu.org\/worldwide-community\/society\/soutenir-le-nouveau-message'   ><span>Faites un don pour aider le Nouveau Message \u00e0 atteindre le monde.<\/span><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce que la Society ? La Society for the New Message from God (la Soci\u00e9t\u00e9 pour le Nouveau Message de Dieu) est une organisation religieuse \u00e0 but non lucratif dont la mission est de pr\u00e9server, de prot\u00e9ger et de pr\u00e9senter le Nouveau Message de Dieu dans le monde. La Society n&rsquo;est affili\u00e9e \u00e0 aucun corpus\u2026 <a class=\"read-more\" href=\"https:\/\/www.v6.newmessage.org\/fr\/worldwide-community\/society\"><span>Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12743,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-leftsidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[],"tags":[615],"_links":{"self":[{"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/pages\/12810"}],"collection":[{"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/comments?post=12810"}],"version-history":[{"count":196,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/pages\/12810\/revisions"}],"predecessor-version":[{"id":29248,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/pages\/12810\/revisions\/29248"}],"up":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/pages\/12743"}],"wp:attachment":[{"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/media?parent=12810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/categories?post=12810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/fr\/wp-json\/wp\/v2\/tags?post=12810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}