{"id":264,"date":"2011-01-24T14:19:22","date_gmt":"2011-01-24T21:19:22","guid":{"rendered":"http:\/\/wp.www.newmessage.org\/?p=264"},"modified":"2016-01-08T17:24:54","modified_gmt":"2016-01-08T17:24:54","slug":"que-son-los-pasos-al-conocimiento","status":"publish","type":"page","link":"https:\/\/www.v6.newmessage.org\/es\/el-mensaje\/volumen-2\/espiritualidad-de-la-comunidad-mayor\/que-son-los-pasos-al-conocimiento","title":{"rendered":"\u00bfQu\u00e9 son los Pasos al Conocimiento?"},"content":{"rendered":"<div><!-- 4.0 --><\/div>\n\n<div class=\"tabgroup \"><ul class=\"tabs\"><li><a href=\"#tabs-1\">Acerca de<\/a><\/li>\n<li><a href=\"#tabs-2\">M\u00e1s<\/a><\/li><\/ul>\n <div id=\"tabs-1\"><br \/>\n<em>Como le fue revelado a<br \/>\nMarshall Vian Summers<br \/>\nel 5 de noviembre de 1993<br \/>\nen Boulder, Colorado, Estados Unidos<\/em><\/p>\n<p>Texto original:\u00a0<a href=\"https:\/\/www.newmessage.org\/the-message\/volume-2\/greater-community-spirituality\/what-is-steps-to-knowledge\">What is Steps to Knowledge?<\/a><\/p>\n<div class=\"toggle toggle-white\"><h4 class=\"trigger \"><span class=\"t_ico\"><\/span><a href=\"#\">M\u00e1s informaci\u00f3n sobre este texto<\/a><\/h4><div class=\"toggle_container \"><br \/>\n<p>Lo que est\u00e1s leyendo en este texto es la transcripci\u00f3n de la voz original de la Asamblea Ang\u00e9lica hablando a trav\u00e9s del Mensajero Marshall Vian Summers.<\/p>\n<p>Aqu\u00ed, la comunicaci\u00f3n original de Dios, que existe m\u00e1s all\u00e1 de las palabras, es traducida al lenguaje y el entendimiento humanos por la Asamblea Ang\u00e9lica que supervisa el mundo. La Asamblea despu\u00e9s entrega el Mensaje de Dios a trav\u00e9s del Mensajero, tras lo cual es transcrito y puesto a tu disposici\u00f3n y a disposici\u00f3n de todos.<\/p>\n<p>En este extraordinario proceso, la Voz de la Revelaci\u00f3n est\u00e1 hablando de nuevo. La Palabra y el Sonido est\u00e1n en el mundo. Que puedas ser el receptor de este regalo de Revelaci\u00f3n y puedas estar abierto a recibir su Mensaje \u00fanico para ti y para tu vida.<\/p>\n<br \/>\n<\/div><\/div>\n<p><\/div>\n<div id=\"tabs-2\"><\/p>\n<div class=\"panel-10 text-align-center\"><img decoding=\"async\" class=\"aligncenter size-full \" src=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2014\/09\/GCS-english-250px.jpg\" alt=\"Greater Community Spirituality\" \/><\/div>\n<div class=\"text-align-center\"><a class='simple_button_link ' style='background-color: #4f8fd6' href='http:\/\/newknowledgelibrary.org\/books\/greater-community-spirituality\/'   ><span>Pide el libro (en ingl\u00e9s)<\/span><\/a><\/div>\n<div class=\"text-align-center text font-size-12 margin-top-10\">Volumen 2 &gt; Espiritualidad de la Comunidad Mayor &gt; Cap\u00edtulo 24<\/div>\n<p><\/div>\n\t\t\t\t<div align=\"right\">\n\t\t\t<div class=\"fb-like\" data-href=\"\" data-layout=\"button_count\" data-action=\"like\" data-show-faces=\"false\" data-share=\"false\"><\/div>\n\t\t\t<div class=\"fb-share-button\" data-layout=\"button_count\"> <\/div>\n\t\t\t<div class=\"fb_iframe_widget\"><a href=\"https:\/\/twitter.com\/godsnewmessage?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-show-count=\"false\">Follow @godsnewmessage<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n\t\t\t<\/div> <\/div> \n\n<p>Aprender Espiritualidad de la Comunidad Mayor requiere preparaci\u00f3n de una clase muy especial. Esta preparaci\u00f3n debe llevarte al mism\u00edsimo coraz\u00f3n de lo que la espiritualidad significa, y aun as\u00ed debe capacitarte para encarar el mundo de forma realista y pr\u00e1ctica, sin negaci\u00f3n ni enga\u00f1o. Debe poder cultivar tus fortalezas, mientras minimiza los riesgos de malentendido y malinterpretaci\u00f3n. Debe apuntarte alto, pero no tan alto que no puedas alcanzar tu objetivo. Debe alimentar tu propia autoridad interna, mientras ganas una percepci\u00f3n de la autoridad mayor en la vida que trasciende tu propio dominio. Debe establecer un contexto en el que todas tus relaciones puedan tener una involucraci\u00f3n significativa y puedan ser entendidas. Esto, entonces, requiere una aproximaci\u00f3n muy \u00fanica, algo que pueda circunvalar, en el m\u00e1ximo grado posible, tus anteriores creencias e ideas y tu condicionamiento por el mundo.<\/p>\n<p>Para aprender la Espiritualidad de la Comunidad Mayor necesitas un camino hacia ella \u2014un camino hacia el Conocimiento\u2014. Todo lo que hemos hablado en este libro y en todos los Libros del Conocimiento te dirige hacia el Conocimiento mismo. Esta es la esencia misma de tu espiritualidad. Este es tu Verdadero Ser mientras existes en la vida f\u00edsica. Este es tu v\u00ednculo con toda la vida, y con la vida que te ha enviado al mundo para servir y reconocer un prop\u00f3sito mayor.<\/p>\n<p>Debe haber un camino al Conocimiento. Para seguir el camino, debes tomar los pasos. No puedes llegar de un salto. No puedes apresurarte. No puedes correr hacia el Conocimiento. Es demasiado grande, y hay demasiadas cosas que aprender y desaprender a lo largo del camino. Hay demasiadas cosas que evaluar y reevaluar. Hay demasiadas comprensiones importantes que obtener. Por lo tanto, debes tomar los pasos al Conocimiento.<\/p>\n<p>Si estuvieras ascendiendo una gran monta\u00f1a, necesitar\u00edas seguir un camino. No puedes simplemente precipitarte hacia arriba por sus terraplenes. Y necesitas una preparaci\u00f3n que te orientar\u00e1 en todas las situaciones que se te presenten. Necesitas una preparaci\u00f3n que te prepare para nuevas experiencias y dificultades y te d\u00e9 una mayor perspectiva, as\u00ed como la paciencia y seguridad que necesitar\u00e1s para seguir tu camino y continuar hacia delante. Solo fracasar\u00e1s en esta preparaci\u00f3n si no te honras a ti mismo o pierdes de vista tu objetivo mayor.<\/p>\n<p>Cuando est\u00e1s en la monta\u00f1a raramente puedes ver la cumbre. Todo lo que ves son tus alrededores inmediatos. Todo lo que sientes son las circunstancias cambiantes de tu viaje. Raramente ver\u00e1s tu destino final. Pero si contin\u00faas, llegar\u00e1s a conocer a la monta\u00f1a misma. Llegar\u00e1s a aprender el camino siguiendo el camino que asciende a la monta\u00f1a. Y llegar\u00e1s a comprender lo que significa cada paso a medida que des cada paso. La reserva, el juicio y la evaluaci\u00f3n nunca te revelar\u00e1n nada que tenga alguna significaci\u00f3n al respecto. Debes hacer el camino, y para hacer el camino debes tomar los pasos, uno por uno. De este modo, tu progreso ser\u00e1 lento y constante. De este modo, todo lo que aprendas ser\u00e1 experimentado y asimilado profundamente. De este modo, no pasar\u00e1s por alto nada que sea verdaderamente esencial para tu desarrollo y tu bienestar.<\/p>\n<p>A medida que procedas, tambi\u00e9n aprender\u00e1s a cultivar las habilidades imprescindibles que necesitar\u00e1s para encarar la vida, para dar a la vida y para entender tu camino en la vida. Estas habilidades son la paciencia, la perseverancia, la compasi\u00f3n, el discernimiento y la discreci\u00f3n. Estas grandes habilidades son necesarias para cualquier logro en cualquier campo, pero para reconocer un prop\u00f3sito mayor en la vida y ser capaz de experimentarlo y aplicarlo de manera efectiva, estas habilidades mayores ser\u00e1n requeridas a\u00fan m\u00e1s, y necesitar\u00e1s poder contar con ellas.<\/p>\n<p>Estas habilidades mayores son necesarias, porque no tendr\u00e1s grandes tomas de consciencia todo el tiempo. No tendr\u00e1s experiencias maravillosas todo el tiempo. No te sentir\u00e1s confiado y tranquilo contigo mismo todo el tiempo. De hecho, puede haber grandes huecos entre estas experiencias. Aqu\u00ed debes contar con tu determinaci\u00f3n y tu perseverancia. Aqu\u00ed debes cultivar una mayor perspectiva y una mayor comprensi\u00f3n que transcienda tus sensaciones, emociones y experiencias inmediatas. Como en el ascenso a una gran monta\u00f1a, tendr\u00e1s momentos de gran dicha y momentos de gran dificultad. Tendr\u00e1s momentos de verdadera certeza y momentos de incertidumbre. Tendr\u00e1s los retos de la vida puestos en tu camino. Y tendr\u00e1s decisiones importantes que tomar \u2014decisiones que afectar\u00e1n al resultado de tu viaje y que determinar\u00e1n las consecuencias de tu vida y de las vidas de otros.<\/p>\n<p>Por tanto, toma los pasos al Conocimiento. S\u00edguelos lentamente. Mu\u00e9vete de manera consistente. No corras hacia delante ni te quedes atr\u00e1s. La consistencia aqu\u00ed es importante, pues te permite aprender a un ritmo que te mantiene movi\u00e9ndote hacia delante. Aqu\u00ed no exceder\u00e1s tus capacidades. No pasar\u00e1s por alto nada que sea importante. No ser\u00e1s indolente, inactivo o inconsistente. La consistencia de seguir los pasos al Conocimiento, de seguir una preparaci\u00f3n que t\u00fa no has inventado o dise\u00f1ado para ti mismo, te dar\u00e1 mayor consistencia en todos los otros aspectos de tu vida, y te permitir\u00e1 ser una \u00fanica persona, la misma persona, en todas las situaciones. Entonces ya no ser\u00e1s m\u00e1s un conglomerado de personalidades escindidas. Te har\u00e1s una \u00fanica persona con un \u00fanico foco y una \u00fanica orientaci\u00f3n.<\/p>\n<p>Las palabras no pueden describir qu\u00e9 experiencia es esta, cu\u00e1nta fuerza y habilidad te dar\u00e1 y c\u00f3mo te liberar\u00e1 de tantas distracciones y seducciones debilitantes que ahora solo te frustran y te agravan. Aqu\u00ed la verdadera profundidad de tu naturaleza, la verdadera profundidad y prop\u00f3sito de tu habilidad y la importancia de tu mente y tu cuerpo ser\u00e1n plenamente comprendidas mediante la experiencia. Aqu\u00ed tu mente no necesitar\u00e1 crear una gran filosof\u00eda sobre la vida, pues estar\u00e1s viviendo la vida y estar\u00e1s cercano a la vida. Solo cuando est\u00e1s removido de la vida y separado de ella necesitas gran cantidad de ideas e idealismo con los que justificar y dirigir tu experiencia. Sin embargo, cuando est\u00e1s cerca de la vida y tu vida es real y genuina, tu mente est\u00e1 libre de esta gran carga. Una mente libre es una mente que puede reenfocarse. Es una mente que puede repensar sus pensamientos y puede responder al entorno. Es una mente que puede conseguir una mayor aplicaci\u00f3n y perspicacia.<\/p>\n<p>Entonces, \u00bfqu\u00e9 son los pasos al Conocimiento? \u00bfC\u00f3mo funcionan? \u00bfD\u00f3nde te llevan? \u00bfY c\u00f3mo pueden ser seguidos con \u00e9xito? <em>Pasos al Conocimiento<\/em> es una preparaci\u00f3n que representa la traducci\u00f3n a la experiencia y el mundo humanos del Camino del Conocimiento de la Comunidad Mayor. Esta traducci\u00f3n llama a la espiritualidad mayor que llevas dentro de tu Conocimiento.<\/p>\n<p><em>Pasos al Conocimiento<\/em> se da en una serie de programas de avance progresivo, que est\u00e1n bien delineados y organizados. Ellos te dan una gran libertad de experiencia. El \u00e9nfasis principal est\u00e1 en seguir cada paso tal y como se da \u2014sin alterarlo de ning\u00fan modo, aplic\u00e1ndote consistentemente y estando determinado a terminar la etapa en la que te encuentras\u2014. Esto ser\u00e1 un desaf\u00edo lo suficientemente grande por s\u00ed mismo, porque puede que est\u00e9s tentado de cambiar la preparaci\u00f3n para satisfacer tus ideas actuales, tranquilizarte a ti mismo o mantener las cosas dentro de un marco familiar. Sin embargo, <em>Pasos al Conocimiento<\/em> te llevar\u00e1 m\u00e1s all\u00e1 de lo familiar hacia un territorio nuevo, m\u00e1s all\u00e1 de d\u00f3nde est\u00e1s hoy hacia algo mayor para ma\u00f1ana, m\u00e1s all\u00e1 de tus entendimiento y capacidades actuales hacia un conjunto m\u00e1s grande de capacidades y un entendimiento mayor.<\/p>\n<p>Aqu\u00ed debes estar dispuesto a ir m\u00e1s all\u00e1 de tus ideas fijas y las creencias que aprecias. Aqu\u00ed entrar\u00e1s en una nueva experiencia en la que no est\u00e1s seguro de qui\u00e9n eres, por qu\u00e9 est\u00e1s aqu\u00ed o qu\u00e9 est\u00e1s haciendo. Sin embargo, esta incertidumbre no es permanente. Representa una transici\u00f3n desde una comprensi\u00f3n a otra. T\u00fa pasar\u00e1s por muchas de estas transiciones a medida que tu mente gana un punto de vista en la vida cada vez m\u00e1s alto. Usando la analog\u00eda de la monta\u00f1a, t\u00fa no tendr\u00e1s una posici\u00f3n panor\u00e1mica todo el tiempo, desde la que puedas ver a d\u00f3nde vas y d\u00f3nde has estado. M\u00e1s bien, la mayor\u00eda de las veces necesitar\u00e1s focalizarte en tomar los pasos ante ti y tratar con el viaje mismo, y no siempre tendr\u00e1s confirmaci\u00f3n sobre d\u00f3nde te encuentras en un momento dado.<\/p>\n<p>Aqu\u00ed el Conocimiento es tu gu\u00eda. El Conocimiento es fuerte y consistente. Es puro y no le afecta el mundo. \u00c9l te da una mayor fortaleza, una mayor motivaci\u00f3n y una mayor capacidad en la vida \u2014mayor en un grado tan alto que nada puede compar\u00e1rsele\u2014. Y de sus muchas grandes recompensas, la mayor es la unificaci\u00f3n dentro de ti mismo, pues al fin sentir\u00e1s que tu vida es real y que est\u00e1s haciendo lo que viniste a hacer aqu\u00ed. Sin importar lo inexplicable que tu viaje pueda parecer ni lo confusos que puedan ser los eventos de tu vida, est\u00e1s tomando los pasos al Conocimiento. Te est\u00e1s acercando a tu realidad interna. Te est\u00e1s haciendo capaz de implicarte con el mundo de una manera m\u00e1s realista, m\u00e1s sobria, m\u00e1s efectiva y m\u00e1s compasiva. Tu compasi\u00f3n nacer\u00e1 de tu experiencia de hacer un viaje como este, pues aqu\u00ed tomar\u00e1s consciencia de lo que retiene a la gente. Comprender\u00e1s lo que significa realmente la libertad y c\u00f3mo debe ganarse y asegurarse en la vida.<\/p>\n<p>Los pasos al Conocimiento son espec\u00edficos. Te son presentados en el programa <em>Pasos al Conocimiento<\/em>. Solo necesitas seguirlos sin alterarlos. Y a medida que aprendas a seguirlos, aprender\u00e1s a seguirlos a su ritmo, el cual puede que sea un ritmo m\u00e1s r\u00e1pido y m\u00e1s consistente que aquel al que est\u00e1s acostumbrado, pero ser\u00e1 un ritmo que puedes seguir. No estar\u00e1 m\u00e1s all\u00e1 de tus capacidades, aunque exceder\u00e1 lo que has conseguido hasta ahora.<\/p>\n<p>Cada brizna de progreso que hagas siguiendo los <em>Pasos al Conocimiento<\/em> tendr\u00e1 un impacto inmediato en tu vida y en tus circunstancias. Pues si desarrollas certeza y capacidad en un \u00e1rea, entonces eventualmente esto se transferir\u00e1 a las otras \u00e1reas de tu vida. T\u00fa no quieres vivir una vida de contradicci\u00f3n. T\u00fa querr\u00e1s cada vez m\u00e1s que tu vida sea una expresi\u00f3n uniforme de verdad y significado. Esto te permitir\u00e1 traducir el Conocimiento y la Sabidur\u00eda a m\u00e1s y m\u00e1s aspectos de tu vida. Seg\u00fan lo hagas, te har\u00e1s m\u00e1s y m\u00e1s fuerte en el Conocimiento, pues el Conocimiento estar\u00e1 emanando de ti, no solo aqu\u00ed y all\u00ed, no simplemente en esta o en esa circunstancia, sino cada vez m\u00e1s y de manera m\u00e1s completa.<\/p>\n<p>El Conocimiento es la Gran Presencia que llevas contigo. Y a medida que te abres a ella y permites que te demuestre su realidad, te har\u00e1s una expresi\u00f3n de su vida, que es tu verdadera vida en el mundo. Aqu\u00ed te entregas a la Realidad Mayor dentro de ti. Aqu\u00ed te entregas a aquello que es la \u00fanica cosa a la que puedes entregarte, la \u00fanica cosa a la que puedes dedicarte, y esta cosa es el Conocimiento en ti y el Conocimiento en otros. Esta es la verdad que envuelve a toda vida manifiesta y se mantiene cierta a lo largo y ancho del universo, en todas las dimensiones y realidades. Esta es la verdad que te restaura lo que viniste a dar aqu\u00ed y lo que viniste a comprender.<\/p>\n<p>El camino es simple, pero dificultoso. Es simple, porque solo necesitas seguir los pasos. Aqu\u00ed se te da un mapa para ascender la monta\u00f1a. Y se te pide que no te desv\u00edes de este mapa, que lo sigas de forma segura y consistente. Sin embargo, es dif\u00edcil, porque la gente no est\u00e1 acostumbrada a seguir algo sin alterarlo para satisfacer sus referencias pasadas. Es dif\u00edcil, porque debes entregarte a tu preparaci\u00f3n y debes confiar en tu preparaci\u00f3n. Tanto en esos momentos en los que es maravillosa como en aquellos en los que es dif\u00edcil, debes acercarte a ella con la misma confianza y la misma consistencia. Esto genera un poder tremendo dentro de ti. Esto te permite y de hecho te demanda que ejercites tu propia autoridad individual sobre tus pensamientos e intentos. Esto es necesario para vivir una vida verdadera y significativa. Y esto es lo que te llevar\u00e1 a tu llamada y prop\u00f3sito mayores, pues esto pone la fundaci\u00f3n para que surjan esta llamada y prop\u00f3sito.<\/p>\n<p>Seg\u00fan avances y te hagas m\u00e1s maduro en tu comprensi\u00f3n y participaci\u00f3n, entonces, y solo entonces, tu llamada comenzar\u00e1 lentamente a tomar forma. Esta no ser\u00e1 una definici\u00f3n. Y no ser\u00e1 algo que vaya a serte revelado todo de una vez. Ser\u00e1 algo que encontrar\u00e1s a medida que aquellas cosas que son innecesarias o carecen de significado en tu vida se desmoronen o renuncies a ellas. Lo que queda es lo esencial. Entonces eres libre para encontrar tu camino a aquello que debes comprender. Esta es la manera de encontrarlo, pues no puedes encontrarlo de ning\u00fan otro modo. No solo debes llegar a los grandes descubrimientos acerca de tu vida; debes aprender el camino hacia ellas, pues hacerlo te ense\u00f1ar\u00e1 c\u00f3mo ayudar a otros a encontrar su camino hacia sus grandes descubrimientos en la vida. Debes aprender el camino para poder mostrar el camino y compartir el camino, para fortalecer a aquellos que est\u00e1n detr\u00e1s de ti y para reconocer a aquellos que est\u00e1n muy por delante.<\/p>\n<p><em>Pasos al Conocimiento<\/em>, por tanto, es tanto f\u00e1cil como dif\u00edcil. Es f\u00e1cil porque es directo. Es f\u00e1cil porque no necesitas definir el camino. Es f\u00e1cil porque te protege de muchos errores y calamidades que solo podr\u00edan frustrar tu intento y conducirte al fracaso o al desastre. Sin embargo, el camino simple es dif\u00edcil porque la gente no es simple. Ser simple significa tener confianza y ser capaz de discernir aquello que justifica tu confianza de aquello que no la justifica. Ser simple significa entregarte por entero y ser capaz de tomar el control de tu vida y conducirla con efectividad. Ser simple significa tener una mente focalizada y libre que no est\u00e1 cargada con evaluaciones innecesarias y que no est\u00e1 intentando llevar el gran peso de las experiencias o las expectativas de otras personas. Tu mente funcionar\u00e1 a un nivel muy superior cuando se libere de estas cosas.<\/p>\n<p>Seg\u00fan esto ocurra, tus relaciones ser\u00e1n refinadas y redefinidas, y aquellos individuos que son tus verdaderos compa\u00f1eros en la vida encontrar\u00e1n su camino hasta ti. Y t\u00fa ser\u00e1s capaz de reconocerles y recibirles, pues t\u00fa mismo estar\u00e1s haciendo el camino. Esto te mostrar\u00e1 c\u00f3mo discernir el significado en las relaciones, pues el significado en las relaciones solo puede ser discernido siguiendo algo de mayor importancia y magnitud en la vida.<\/p>\n<p>El discernimiento, entonces, se vuelve no un asunto de enjuiciamiento y cr\u00edtica, sino un medio para el reconocimiento. En vez de bueno o malo, se vuelve s\u00ed o no. Sabes qu\u00e9 seguir y qu\u00e9 no seguir. Sabes con qui\u00e9n estar y con qui\u00e9n no estar \u2014todo esto sin juzgar ni condenar\u2014. Qu\u00e9 simple es esto y qu\u00e9 directo y natural. Qu\u00e9 confirmador de la vida es esto para ti, que puedes recibirlo. Pero qu\u00e9 dif\u00edcil puede parecer si est\u00e1s acostumbrado a intentar negociar tu vida, a realizar tus propios objetivos o a establecer tu propio camino bas\u00e1ndote en tus preferencias y temores. Qu\u00e9 dif\u00edcil es esto cuando est\u00e1s intentando manipular tu propia mente y las mentes de los dem\u00e1s.<\/p>\n<p>El Camino del Conocimiento de la Comunidad Mayor te ense\u00f1ar\u00e1 a hacerte simple y poderoso. Te aliviar\u00e1 de ser artificioso y d\u00e9bil. El Camino del Conocimiento te ense\u00f1ar\u00e1 a hacerte fuerte y penetrante en tus capacidades. Te liberar\u00e1 del peso de ser superficial y difractado.<\/p>\n<p>Los pasos al Conocimiento son misteriosos. No podr\u00e1s entenderlos hasta que hayas hecho buena parte del camino y puedas mirar hacia atr\u00e1s y ver d\u00f3nde te han llevado. Igual que en el ascenso a una gran monta\u00f1a, \u00bfqu\u00e9 significado tiene cada paso hasta que ves d\u00f3nde te ha llevado y qu\u00e9 te ha dado?<\/p>\n<p>Por tanto, a medida que tomes los pasos al Conocimiento, no los juzgues. Algunos te gustar\u00e1n, y otros puede que no te gusten. Algunos te parecer\u00e1n familiares, y otros te parecer\u00e1n nuevos. Sin embargo, no los juzgues, pues no puedes entenderlos hasta que comprendas a d\u00f3nde te est\u00e1n llevando. Y no puedes descubrir a d\u00f3nde te est\u00e1n llevando a menos que los sigas. Este es el camino a trav\u00e9s de la jungla de la vida. El sendero es estrecho. Es espec\u00edfico. Te lleva a trav\u00e9s de situaciones peligrosas. Te lleva a trav\u00e9s de atracciones. Te lleva a trav\u00e9s de la disociaci\u00f3n. Te lleva a trav\u00e9s de todas las formas de distracci\u00f3n. Te lleva a trav\u00e9s de estas cosas y m\u00e1s all\u00e1 de ellas. Por tanto, para comprender los pasos al Conocimiento debes ver d\u00f3nde te est\u00e1n llevando y debes ir a donde te llevan.<\/p>\n<p><em>Pasos al Conocimiento <\/em>y el Camino del Conocimiento de la Comunidad Mayor son ambos algo enteramente nuevo y diferente. Quienquiera que seas y sea lo que sea que pienses que has conseguido y aprendido en la vida, tendr\u00e1s que comenzar aqu\u00ed como principiante. Olvida lo que has aprendido y comienza de nuevo. Hazlo y aprender\u00e1s lo m\u00e1ximo que puede ser aprendido. Si no lo haces, intentar\u00e1s simplemente evaluar todo lo que ocurra y cada paso que des de acuerdo a tus referencias pasadas. Esto te mantendr\u00e1 en el pasado y te impedir\u00e1 venir al presente y moverte hacia el futuro. <em>Pasos al Conocimiento<\/em> te libera del pasado d\u00e1ndote una manera de salir de tu pasado y del pasado del mundo. Pues nada del pasado puede conducirte con efectividad hacia el futuro.<\/p>\n<p>El Camino del Conocimiento de la Comunidad Mayor representa el presente y el futuro. Es una preparaci\u00f3n para vivir plenamente en el presente y prepararse plenamente para el futuro, de modo que en el futuro uno tenga la oportunidad de vivir en el presente. Es por esto que lo f\u00e1cil parece dif\u00edcil. Para seguir aquello que es f\u00e1cil, debes hacerte simple y encontrar escape de las complejidades de tu vida que solo te mantienen encadenado al pasado y a un estado de ambivalencia. Para viajar hacia la vida debes seguir un camino diferente.<\/p>\n<p>Por tanto, comienza como un principiante. No asumas que sabes mucho, pues en realidad no sabes mucho. No asumas que tienes grandes capacidades, pues en un contexto mayor de la vida t\u00fa no tienes grandes capacidades. Acepta tu condici\u00f3n con humildad, sin condena. De esta manera, te abres a aprender aquello que solo puedes aprender abri\u00e9ndote. No juzgues los pasos, pues t\u00fa no puedes juzgarlos. Ellos te est\u00e1n sacando de tu pasado. No son una confirmaci\u00f3n de tu pasado.<\/p>\n<p>Tu pasado es lo que est\u00e1 detr\u00e1s de ti. El futuro es lo que est\u00e1 por delante. El presente es c\u00f3mo experimentas tu relaci\u00f3n con el pasado y el futuro. Para experimentar el presente, debes tener una correcta relaci\u00f3n con ambos, el pasado y el futuro, o nunca ser\u00e1s capaz de entrar en el presente por completo. El Conocimiento est\u00e1 en el presente en todo momento. \u00c9l representa un estado de mente completamente presente. \u00c9l es el \u00fanico estado de mente presente. Cuanto m\u00e1s cerca est\u00e1s del Conocimiento, m\u00e1s presente est\u00e1s respecto a la vida. Y aun as\u00ed, tu estado de mente presente est\u00e1 plenamente unido al movimiento del mundo y al futuro del mundo. No es algo que t\u00fa inventas para ti como un ejercicio psicol\u00f3gico o como una forma de escape de un mundo que no puedes aceptar o experimentar. Eso solo conduce a la desilusi\u00f3n y a una mayor disociaci\u00f3n respecto de la vida.<\/p>\n<p><em>Pasos al Conocimiento<\/em> te lleva a la vida tal como es y tal como ser\u00e1. Te lleva a tu vida tal como es y tal como ser\u00e1. Te permite involucrarte con otros tal como ellos son y tal como ser\u00e1n. Qu\u00e9 simple es esto, pero qu\u00e9 dif\u00edcil puede parecer al principio. A medida que aprendes a tomar los pasos al Conocimiento y a seguirlos con efectividad, tu carga se har\u00e1 m\u00e1s ligera, pues tu mente se liberar\u00e1 de aquello que es innecesario para su felicidad y satisfacci\u00f3n. Tu vida quedar\u00e1 libre de compromisos da\u00f1inos y b\u00fasquedas sin sentido que nunca te han dado lo que verdaderamente buscabas.<\/p>\n<p>Estas cosas caen de forma natural. No te son quitadas. T\u00fa las dejas a un lado porque no puedes llevarlas contigo a una mayor experiencia de la vida. Son dejadas en la puerta. Renuncias a ellas voluntariamente. Ahora est\u00e1s descargado. El camino se vuelve m\u00e1s simple y m\u00e1s grande. Con esta simplicidad y grandeza, tu experiencia y comprensi\u00f3n se hacen m\u00e1s profundas y penetrantes. Tu mente se vuelve m\u00e1s focalizada y consistente. Tu determinaci\u00f3n se fortalece. Tu discernimiento de otros se vuelve m\u00e1s n\u00edtido y m\u00e1s revelador. Tu capacidad para permanecer tanto con la verdad como con la incertidumbre se hace m\u00e1s y m\u00e1s fuerte. Aqu\u00ed tu capacidad para relacionarte se expande considerablemente. Esto te permite involucrarte con las grandes relaciones con las que est\u00e1s destinado a involucrarte en esta vida. Esto construye dentro de ti una mayor capacidad para la relaci\u00f3n, lo cual te abrir\u00e1 a tu relaci\u00f3n con el Creador y con la Comunidad Mayor de Mundos.<\/p>\n<p>Empezar puede ser dif\u00edcil, pero si puedes empezar, puedes proceder. Si puedes proceder, puedes progresar. Si puedes progresar, puedes avanzar. Si puedes avanzar, entonces puedes comprender todas las etapas que precedieron a esta. Entonces entender\u00e1s lo que significa empezar. Entonces entender\u00e1s lo que significa progresar y avanzar.<\/p>\n<p><em>Pasos al Conocimiento<\/em> no requiere que veneres a ning\u00fan h\u00e9roe o personalidad. No requiere que aceptes una historia de la creaci\u00f3n de la vida que es incre\u00edble e imposible. No requiere que creas en un pante\u00f3n de dioses, im\u00e1genes, s\u00edmbolos, rituales, representaciones y personalidades. <em>Pasos al Conocimiento<\/em> solo te trae a la gran pregunta de qu\u00e9 sabes verdaderamente. Y no contesta esta pregunta con palabras, sino que te lleva hacia la experiencia del Conocimiento mismo, lentamente, a trav\u00e9s de muchos pasos y etapas de desarrollo. Si procedes, avanzar\u00e1s. Si avanzas, comprender\u00e1s. Si comprendes, entonces sabr\u00e1s.<\/p>\n<p><em>Pasos al Conocimiento<\/em> te dar\u00e1 una nueva vida \u2014no una vida que es ajena a ti, sino una vida que es el hogar para ti; no una vida que est\u00e1 ligada a tus experiencias y evaluaciones pasadas, sino una vida que es genuina en este momento y que tiene mayores posibilidades y mayores relaciones\u2014. Esto satisface tus necesidades m\u00e1s fundamentales y tus preguntas m\u00e1s profundas. Las satisface llev\u00e1ndote a su realizaci\u00f3n. Para saber lo que debes saber, para ver lo que debes ver y para hacer lo que debes hacer, debes alcanzar un mayor punto de vista en la vida. Para alcanzarlo debes hacer el viaje, un viaje de muchos pasos. Y los pasos est\u00e1n en <em>Pasos al Conocimiento.<\/em><\/p>\n<p>Hemos provisto los pasos mismos para permitirte aprender un Camino del Conocimiento de la Comunidad Mayor. Ellos te llevar\u00e1n a tu destino, pero debes seguirlos y ser paciente, porque hay muchas cosas que has de aprender a lo largo del camino, muchas de las cuales no est\u00e1n siquiera en tu consciencia. Y hay muchas cosas que debes adquirir y fortalecer por el camino, cosas que no puedes ver al principio.<\/p>\n<p>El Camino del Conocimiento de la Comunidad Mayor puede ser aprendido. Puede ser experimentado. Puede ser integrado. Puede ser aplicado. Y puede ser vivido. Para hacer esto posible, nosotros proveemos los pasos. S\u00edguelos, no ciegamente, sino con los ojos abiertos. S\u00edguelos a donde te lleven, no con grandes presunciones sobre lo que har\u00e1n por ti, sino con un estado de mente presente. Aprende a andar el camino y ver\u00e1s que hay quienes est\u00e1n por delante de ti y quienes est\u00e1n detr\u00e1s. Aquellos por delante te alentar\u00e1n, mostr\u00e1ndote el camino y d\u00e1ndote la fortaleza y la convicci\u00f3n de que debes proceder tanto si comprendes como si no.<\/p>\n<p><em>Pasos al Conocimiento<\/em> te llevar\u00e1 a trav\u00e9s de aquellos momentos de gran transici\u00f3n en los que est\u00e1s inseguro sobre lo que est\u00e1s haciendo y qui\u00e9n eres. Te llevar\u00e1 m\u00e1s all\u00e1 de aquellos puntos en los que te defines a ti mismo y a tu existencia, hacia una mayor experiencia y comprensi\u00f3n. Te llevar\u00e1 a trav\u00e9s de aquellos momentos dif\u00edciles en los que debes tomar decisiones dif\u00edciles. Y te llevar\u00e1 hacia aquellos maravillosos momentos en los que experimentas tu relaci\u00f3n contigo mismo y con otros de una manera enteramente nueva y penetrante.<\/p>\n<p>Aqu\u00ed comprender\u00e1s que est\u00e1s avanzando y que otros est\u00e1n avanzando contigo, no solo en este mundo sino tambi\u00e9n en otros mundos. Pues el Camino del Conocimiento de la Comunidad Mayor y los <em>Pasos al Conocimiento<\/em> est\u00e1n siendo ense\u00f1ados en muchos mundos \u2014m\u00e1s de los que puedes contar\u2014. Esto representa el Plan Mayor del Creador y una misi\u00f3n y prop\u00f3sito mayores en la vida para restaurar el universo a su estado de pura uni\u00f3n y simplicidad.<\/p>\n<p class=\"NMBody\">T\u00fa, entonces, est\u00e1s siguiendo un Antiguo Rito de preparaci\u00f3n, nacido de la Gran Voluntad del universo. La preparaci\u00f3n en el Camino del Conocimiento de la Comunidad Mayor est\u00e1 siendo provista para ti y para tu mundo \u2014un camino del Conocimiento no solo hacia el misterio de tu vida, sino hacia la grandeza de la Comunidad Mayor a la que tu vida est\u00e1 ahora emergiendo\u2014. Esto representa una mayor posibilidad para ti que est\u00e1s leyendo estas palabras, porque est\u00e1s respondiendo a una llamada y un significado mayores en la vida \u2014una llamada y un significado que t\u00fa has tra\u00eddo contigo, que residen dentro de ti y que deben ser ahora sacados de ti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprender Espiritualidad de la Comunidad Mayor requiere preparaci\u00f3n de una clase muy especial. Esta preparaci\u00f3n debe llevarte al mism\u00edsimo coraz\u00f3n de lo que la espiritualidad significa, y aun as\u00ed debe capacitarte para encarar el mundo de forma realista y pr\u00e1ctica, sin negaci\u00f3n ni enga\u00f1o. Debe poder cultivar tus fortalezas, mientras minimiza los riesgos de malentendido\u2026 <a class=\"read-more\" href=\"https:\/\/www.v6.newmessage.org\/es\/about-text-shortcode\"><span>Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13081,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"template-leftsidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44,468,76,77,467],"tags":[],"_links":{"self":[{"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/pages\/264"}],"collection":[{"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":12,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/pages\/264\/revisions"}],"predecessor-version":[{"id":27224,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/pages\/264\/revisions\/27224"}],"up":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/pages\/13081"}],"wp:attachment":[{"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/media?parent=264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/categories?post=264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/es\/wp-json\/wp\/v2\/tags?post=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}