{"id":28982,"date":"2020-08-24T08:00:48","date_gmt":"2020-08-24T08:00:48","guid":{"rendered":"https:\/\/www.newmessage.org\/de\/?page_id=28982"},"modified":"2020-08-24T18:56:10","modified_gmt":"2020-08-24T18:56:10","slug":"menschliche-reaktionen-auf-die-grosere-gemeinschaft","status":"publish","type":"page","link":"https:\/\/www.v6.newmessage.org\/de\/die-botschaft\/band-2\/vorbereitung-auf-die-grosere-gemeinschaft\/menschliche-reaktionen-auf-die-grosere-gemeinschaft\/","title":{"rendered":"Menschliche Reaktionen auf die Gr\u00f6\u00dfere Gemeinschaft"},"content":{"rendered":"<div><!-- 7.06 Menschliche Reaktionen auf die Gr\u00f6\u00dfere Gemeinschaft --><\/div>\n\n<div class=\"tabgroup \"><ul class=\"tabs\"><li><a href=\"#tabs-1\">\u00dcber<\/a><\/li>\n<li><a href=\"#tabs-2\"> Anmerkung<\/a><\/li><\/ul>\n <div id=\"tabs-1\"><\/p>\n<p><a href=\"https:\/\/www.community.newmessage.org\/human-responses-to-the-greater-community\/\"><img decoding=\"async\" src=\"https:\/\/www.newmessage.org\/wp-content\/uploads\/2020\/06\/PGC-13-Human-Responses-to-the-Greater-Community-300x157.jpeg\" alt=\"Human Responses to the Greater Community\" class=\"aligncenter size-medium wp-image-48547 imgborder\" \/><\/a><\/p>\n<p><em>Wie offenbart Gottes Boten<br \/>\nMarshall Vian Summers<br \/>\nam 5. Februar 1997<br \/>\nin Boulder, Colorado, USA<\/em><\/p>\n<div class=\"toggle toggle-white\"><h4 class=\"trigger \"><span class=\"t_ico\"><\/span><a href=\"#\">\u00dcber diesen Text<\/a><\/h4><div class=\"toggle_container \"><br \/>\n<p>Was du in diesem Text liest, ist die Transkription der Originalstimme des <a href=\"https:\/\/www.newmessage.org\/de\/wichtige-begriffe#aa\">Engelsrates<\/a>, wie sie \u00fcber den <a href=\"http:\/\/www.neuebotschaft.org\/der-bote\/\">Boten Marshall Vian Summers<\/a> sprach.<\/p>\n<p>Hierbei wird die originale Kommunikation von Gott, die jenseits von Worten existiert, vom <a href=\"https:\/\/www.newmessage.org\/de\/wichtige-begriffe#aa\">Engelsrat<\/a>, der \u00fcber die Welt wacht, in menschliche Sprache und menschliches Verst\u00e4ndnis \u00fcbersetzt. Der Rat bringt dann Gottes Botschaft \u00fcber den Boten dar, woraufhin sie transkribiert und euch und allen Menschen verf\u00fcgbar gemacht wird.<\/p>\n<p>In diesem bemerkenswerten Prozess spricht die <a href=\"https:\/\/www.newmessage.org\/de\/wichtige-begriffe#voice\">Stimme der Offenbarung<\/a> erneut. Das Wort und der Klang sind in der Welt. M\u00f6gest du der Empf\u00e4nger dieses Geschenks der Offenbarung sein und m\u00f6gest du offen sein, ihre einmalige Botschaft f\u00fcr dich und f\u00fcr dein Leben zu empfangen.<\/p>\n<br \/>\n<\/div><\/div>\n<p><\/div>\n<div id=\"tabs-2\"><br \/>\n<em> Anmerkung an den Leser:<br \/>\nDiese \u00dcbersetzung wurde der Society von einem Sch\u00fcler der Neuen Botschaft verf\u00fcgbar gemacht, der den englischen Originaltext als Freiwilliger \u00fcbersetzt hat. Wir stellen diese \u00dcbersetzung in dieser fr\u00fchen Form zur Verf\u00fcgung, damit jeder Gelegenheit hat, sich mit einem Teil der Neuen Botschaft in seiner eigenen Sprache zu befassen.<\/em><br \/>\n<\/div>\n\t\t\t\t<div align=\"right\">\n\t\t\t<div class=\"fb-like\" data-href=\"\" data-layout=\"button_count\" data-action=\"like\" data-show-faces=\"false\" data-share=\"false\"><\/div>\n\t\t\t<div class=\"fb-share-button\" data-layout=\"button_count\"> <\/div>\n\t\t\t<div class=\"fb_iframe_widget\"><a href=\"https:\/\/twitter.com\/godsnewmessage?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-show-count=\"false\">Follow @godsnewmessage<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n\t\t\t<\/div> <\/div> \n\n<p>Es wird einige Zeit dauern, bis sich die Menschen an diese Vorstellung von der Gr\u00f6\u00dferen Gemeinschaft gew\u00f6hnen k\u00f6nnen. Sie stellt eine so gro\u00dfe Schwelle, einen so enormen Wendepunkt f\u00fcr die Menschheit dar. Einige Menschen werden sich darauf zubewegen, andere werden sich davon abwenden, wieder andere werden sich gegen sie wenden. Das sind die drei m\u00f6glichen Reaktionen, die jeder Mensch auf neue Vorstellungen und neue Erfahrungen haben kann. Innerhalb jeder dieser drei m\u00f6glichen Reaktionen gibt es mehrere verschiedene Manifestationen. Schauen Wir uns nun an, was jede davon bedeutet und woher diese Reaktionen in der Person und in der menschlichen Gesellschaft selbst kommen.<\/p>\n<p>Die erste Reaktion auf die Gr\u00f6\u00dfere Gemeinschaft w\u00e4re, sich von ihr abzuwenden. Die Menschen haben eine bemerkenswerte Tendenz, Dinge zu leugnen\u2014Dinge zu leugnen, die immer gegenw\u00e4rtig sind, Dinge zu leugnen, die kritische Probleme in der Welt darstellen, Dinge zu leugnen, die chronische Schwierigkeiten sind, sich so zu verhalten, als ob sie nicht da w\u00e4ren oder vorzugeben, dass sie die Kontrolle \u00fcber etwas haben, wenn sie es eigentlich gar nicht haben.<\/p>\n<p>Weil die Gr\u00f6\u00dfere Gemeinschaft ein enormer Wandel in der Wahrnehmung und im Verst\u00e4ndnis darstellt und weil die Gr\u00f6\u00dfere Gemeinschaft einen solch enormen Wandel in der Wahrnehmung und im Verst\u00e4ndnis erfordert, wird es viel Leugnung geben. Viele Menschen werden einfach \u00fcberhaupt nicht daran denken wollen. Und obwohl die Beweise daf\u00fcr, dass in der Welt viele nicht erbetene Besuche vor sich gehen und dass viele dieser Besucher sich in menschliche Angelegenheiten einmischen, jeden Tag zunehmen, tun die Menschen so, als ob \u00fcberhaupt nichts passiert. Sie gehen ihren eigenen Angelegenheiten nach, sind mit ihren eigenen pers\u00f6nlichen Angelegenheiten besch\u00e4ftigt. Sie werden einfach nicht zulassen, dass dies in ihr Bewusstsein kommt.<\/p>\n<p>Diese Art der Leugnung ist in der Welt sehr verbreitet. Die Menschen wollen es nicht wissen. Wieso ist das so? Woher kommt das? Warum gibt es diese Tendenz bei Menschen in so hohem Ma\u00dfe?<\/p>\n<p>In der menschlichen Natur gibt es einen Schutz vor Schmerzen und es besteht eine gewisse Notwendigkeit, dass die Menschen in der Lage sind, eine Art von Kontrolle \u00fcber ihre Angelegenheiten zu erlangen. Das erzeugt eine Stabilit\u00e4t f\u00fcr den Einzelnen. Das h\u00e4lt die Motivation des Individuums, zu leben und produktiv zu sein, in einem funktionierenden Zustand. Und doch wirkt der Mechanismus, der den Menschen sch\u00fctzt und bewahrt, auch gegen ihn, denn er kann genau die Umst\u00e4nde und Ereignisse leugnen, die das Wohlergehen der Menschen bedrohen und die ihre wirkliche F\u00e4higkeit, die Kontrolle \u00fcber ihr Leben auszu\u00fcben, untergraben w\u00fcrden.<\/p>\n<p>Wenn man die menschliche Geschichte betrachtet, sieht man die Beweise daf\u00fcr, dass die Menschen in Zeiten der Herausforderung oder des Wandels in enormer Leugnung waren. Sie taten so, als ob nichts geschehen w\u00e4re oder wenn sie zugeben mussten, dass etwas geschah, dass sie tats\u00e4chlich die Verantwortung daf\u00fcr tragen und alles gut ausgehen w\u00fcrde.<\/p>\n<p>In einigen F\u00e4llen appellierten sie an eine H\u00f6here Macht und sagten: &#8220;Gott ist daf\u00fcr verantwortlich&#8221; und &#8220;Gott wird sich darum k\u00fcmmern&#8221; und &#8220;Gott wird ein gl\u00fcckliches Ergebnis produzieren&#8221;. Doch dieser Versuch, ihr Wohlbefinden zu erhalten, brachte sie tats\u00e4chlich in Gefahr. Es machte sie tats\u00e4chlich anf\u00e4lliger f\u00fcr Unheil in der Welt.<\/p>\n<p>Deshalb gibt es in jedem Menschen einen bestimmten Schutzmechanismus, der es ihm nicht erlaubt, zu viel Schmerz oder zu viel Unsicherheit zu erfahren. Und doch ist dies genau der Mechanismus, der die Menschheit gef\u00e4hrdet und sie daran hindert, ihre Probleme zu l\u00f6sen, solange die Probleme klein sind. Es ist in gewisser Weise genau der Mechanismus, der das Leben schwieriger und gef\u00e4hrlicher macht.<\/p>\n<p>Doch Leugnung ist nicht einfach das Ergebnis eines eingebauten \u00dcberlebensmechanismus. Sie ist auch das Ergebnis der Besorgnis der Menschen. Es ist auch das Ergebnis dessen, zu dem sie ihre Gefolgschaft gegeben haben. Lasst Uns dies erkl\u00e4ren.<\/p>\n<p>Wenn du dich deinen Vorstellungen und Vorlieben hingibst, dann bist du von der Natur deines Ansatzes her im Widerspruch zu den Realit\u00e4ten des Lebens. Du beharrst darauf, dass das Leben dir gibt, was du willst und du wirst das, was beweist, dass deine Betonung falsch ist, entweder leugnen oder vernachl\u00e4ssigen.<\/p>\n<p>Diese Besch\u00e4ftigung mit dem Gl\u00fcck, diese Besch\u00e4ftigung mit der Gefolgschaft zu den eigenen Vorstellungen und \u00dcberzeugungen ist ein sehr gef\u00e4hrlicher Ansatz. Sie zielt nur darauf ab, bestimmte Elemente des Lebens, bestimmte Aspekte des Lebens anzuerkennen und sich mit ihnen zu identifizieren und versucht, alles andere zu verhindern.<\/p>\n<p>Zum Beispiel wollen [die Menschen] wohlhabend, bequem und gl\u00fccklich werden, aber sie erkennen nicht den Kurs, den dies f\u00fcr sie produziert\u2014den Verlust von Vitalit\u00e4t, den Verlust von Beziehungen, den Verlust ihres Seelenlebens. Sie wollen auch nicht in Betracht ziehen, dass dies vielleicht nicht das Beste f\u00fcr sie oder f\u00fcr die Welt ist. Sie haben sich ein Ziel gesetzt und sie wollen die Kosten nicht in Betracht ziehen. Sie wollen nicht in Betracht ziehen, was dies wirklich bedeutet und sie wollen ihr Ziel unerbittlich verfolgen, ohne zu erkennen, dass es sie alles kostet und dass es vielleicht gar nicht f\u00fcr sie bestimmt ist.<\/p>\n<p>Die Idee der Kenntnis ist f\u00fcr sie furchterregend. Die Vorstellung, dass es schwerwiegende Probleme in der Welt gibt, ist etwas, mit dem sie sich nicht auseinandersetzen wollen. Sie sind mit sich selbst und mit ihren eigenen Zielen besch\u00e4ftigt, aber in Folge davon werden sie ihr wahres Selbst, ihren wahren Zweck und ihren wahren Sinn im Leben nicht finden. Und sie werden nicht die Lebensumst\u00e4nde erkennen, die den Ausgang ihrer Existenz und die Zukunft der Menschheit bestimmen.<\/p>\n<p>Das bedeutet grunds\u00e4tzlich, eine Haltung ohne Intelligenz einzunehmen. In der Gr\u00f6\u00dferen Gemeinschaft wird Intelligenz als die Bereitschaft definiert, als der Wunsch und die F\u00e4higkeit, sich anzupassen und etwas zu gestalten. Das ist die Definition von Intelligenz. Es ist nicht die Gr\u00f6\u00dfe des Gehirns. Es geht nicht darum, wie viele Berechnungen man in einer Minute machen kann. Es ist der Wunsch, der Wille und die F\u00e4higkeit, sich anzupassen und etwas zu erschaffen. Man kann nicht etwas erschaffen, wenn man sich nicht anpassen kann, obwohl viele Menschen dies t\u00e4glich versuchen. <\/p>\n<p>Der wirkliche kreative Impuls kommt aus der direkten Auseinandersetzung mit der Welt, etwas zu entwickeln, das in der Welt gebraucht wird, etwas, wozu ihr bef\u00e4higt seid, etwas, wozu ihr die F\u00e4higkeiten habt, es zu entwickeln. Das ist Intelligenz. Intelligenz ist die F\u00e4higkeit, ein Problem zu erkennen und es sofort anzugehen. Es gibt keine andere wirkliche und sinnvolle Definition von Intelligenz.<\/p>\n<p>Die Demonstration von Intelligenz ist die F\u00e4higkeit, Probleme auf kreative Art und Weise zu l\u00f6sen und dadurch den Zustand der Existenz sowohl f\u00fcr sich selbst als auch f\u00fcr andere zu verbessern. Und doch zeigt Leugnung in all ihren Formen und Manifestationen einen tiefgreifenden Mangel an Intelligenz. Wenn ihr das, was euch die Realit\u00e4t vor Augen f\u00fchrt, vermeidet oder euch dagegen wehrt, \u00fcbt ihr eure Intelligenz nicht aus. Ihr verliert eure Intelligenz und mit eurer Intelligenz verliert ihr die F\u00e4higkeit, euch anzupassen und etwas zu erschaffen.<\/p>\n<p>Hier wird das Streben nach Gl\u00fcck zur Wurzel allen \u00dcbels, nicht weil es von Natur aus schlecht ist, sondern weil die Menschen davon besessen sind und alles andere ausschlie\u00dfen und was sie f\u00fcr ihr Streben einb\u00fc\u00dfen, ist so gro\u00df und so bedeutsam und so wichtig f\u00fcr ihr Wohlergehen und ihre Erf\u00fcllung.<\/p>\n<p>Viele Menschen werden sich von der Gr\u00f6\u00dferen Gemeinschaft abwenden. Sie haben ihre eigenen Vorstellungen. Sie haben ihre eigenen Ziele. Sie wollen nicht, dass das Leben ihre Pl\u00e4ne durchkreuzt. Sie werden dies einfach in ihrem Bewusstsein blockieren oder sie werden leugnen, dass sie existiert. Oder wenn sie nicht leugnen k\u00f6nnen, dass sie existiert, werden sie sie in etwas Angenehmes verwandeln, in etwas Gutes, etwas, mit dem sie sich identifizieren k\u00f6nnen, etwas, das ihre pers\u00f6nlichen Pl\u00e4ne und Ziele unterst\u00fctzt.<\/p>\n<p>Dies geschieht in der heutigen Welt. Viele Menschen glauben: &#8220;Oh, der Besuch von anderen Formen intelligenten Lebens ist ein gro\u00dfes spirituelles Ereignis&#8221;\u2014etwas, das ihre Ideale erf\u00fcllt, etwas, das ihnen das Gef\u00fchl von Erleuchtung, Hoffnung und Frieden gibt, das sie in ihrem eigenen Leben suchen. Doch selbst diese Ziele, die in gewisser Weise den wahren Sinn des Lebens darstellen, werden hier falsch verstanden und fehlinterpretiert.<\/p>\n<p>Um die wirkliche M\u00f6glichkeit f\u00fcr Frieden zu sehen\u2014Gleichmut zu entwickeln, mehr Harmonie in die menschliche Familie zu bringen\u2014muss man mit der Realit\u00e4t arbeiten, wie sie wirklich ist. Ihr k\u00f6nnt eure Ideale oder Werte nicht \u00fcberordnen, denn das Leben wird nicht darauf reagieren und ihr werdet den Kontakt sowohl zu eurer wahren Natur in euch selbst als auch zur Realit\u00e4t des Lebens um euch herum verlieren. Ihr werdet euch vom Leben und von euch selbst entfremden und genau die Ideale, von denen ihr dachtet, sie w\u00fcrden euch die gr\u00f6\u00dferen Belohnungen des Lebens geben, werden euch in Wirklichkeit dessen berauben.<\/p>\n<p>Es gibt heute viele Menschen auf der Welt, die hoffen und glauben, dass die Anwesenheit der Gr\u00f6\u00dferen Gemeinschaft hier Frieden und Gleichmut und eine wahre L\u00f6sung f\u00fcr das menschliche Leben bringen wird. Sie wollen die wirkliche Situation nicht sehen. Sie wollen nur sehen, was sie sehen wollen und das bedeutet nicht sehen. Sie wollen nur denken, was sie denken wollen, aber das ist kein Denken.<\/p>\n<p>Sie \u00fcben hier ihre Intelligenz nicht aus. Sie wenden sich nicht an die Kenntnis in ihnen, um die wirkliche Wahrheit zu enth\u00fcllen. Sie \u00f6ffnen ihre Augen nicht, um die Dinge so zu sehen, wie sie wirklich sind. Dies ist eine Form der Leugnung. Das entfernt sie von der Realit\u00e4t. Das ist die Vermeidung von Sinn, Zweck und Natur des Lebens.<\/p>\n<p>Wenn Wir also sagen, da\u00df die Menschen sich von der Gr\u00f6\u00dferen Gemeinschaft abwenden, kann sich dies auf viele verschiedene Arten manifestieren. Viele werden sich einfach abwenden in dem Glauben, dass dies nicht existiert und f\u00fcr sie wird es nicht genug Beweise in der Welt geben, um sie zu \u00fcberzeugen. Wenn ihr Leben nicht \u00fcberholt wird, werden sie die Realit\u00e4t, dass die Gr\u00f6\u00dfere Gemeinschaft in der Welt ist und dort einen gro\u00dfen Einfluss aus\u00fcbt, leugnen und vermeiden.<\/p>\n<p>Andere werden dies als eine M\u00f6glichkeit in Betracht ziehen, aber ihre Schlussfolgerungen werden nur getroffen, um ihre Vorstellungen und ihre \u00dcberzeugungen zu bekr\u00e4ftigen. Sie wollen nicht, dass ihre Weltanschauung bedroht oder in Frage gestellt wird. Sie wollen nur, dass das Leben sie best\u00e4tigt und so werden sie die Beweise daf\u00fcr, dass die Gr\u00f6\u00dfere Gemeinschaft in der Welt ist, nutzen, um ihre Weltanschauung zu best\u00e4tigen, was immer sie auch sein mag. Sie werden anerkennen, dass sie eine Realit\u00e4t ist, aber sie werden sie so auslegen, dass sie ihren pers\u00f6nlichen Interessen und Zielen dient.<\/p>\n<p>Sie werden sich umdrehen und schauen, aber sie werden nicht sehen, denn sie werden nur ihre Gedanken und ihre \u00dcberzeugungen sehen, unf\u00e4hig, \u00fcber sie hinaus zu sehen. Das bedeutet Leugnung und Vermeidung\u2014eine Unf\u00e4higkeit, sich auf das Leben, so wie es wirklich ist, einzulassen, eine Unf\u00e4higkeit, den Verstand zu \u00f6ffnen und etwas Neues in Betracht zu ziehen, eine Unf\u00e4higkeit, dem Leben gegen\u00fcber verwundbar zu sein, eine Unf\u00e4higkeit, mit der Entwicklung von neuen St\u00e4rken und F\u00e4higkeiten zu beginnen.<\/p>\n<p>Viele Menschen werden sich abwenden. Andere Menschen werden sich gegen die Gr\u00f6\u00dfere Gemeinschaft stellen. Unf\u00e4hig, wegzugehen oder ihre Existenz zu leugnen, werden sie gegen sie k\u00e4mpfen. Sie werden glauben, dass die Besucher hier sind, um sie zu zerst\u00f6ren. Sie werden vielleicht glauben, dass die Besucher d\u00e4monische Kr\u00e4fte darstellen und werden versuchen, ihre Anwesenheit hier auf der Grundlage alter religi\u00f6ser Lehren in der Welt zu interpretieren.<\/p>\n<p>In gewissem Sinne \u00fcben sie sich auch in der Vermeidung, weil sie nicht erkennen k\u00f6nnen, dass die Besucher f\u00fchlende Wesen wie sie selbst sind, getrieben von ihren eigenen Bed\u00fcrfnissen und Sorgen, wie sie selbst. Sie werden sie in D\u00e4monen verwandeln, in die Agenten des Satans.<\/p>\n<p>Sie werden die Realit\u00e4t der Gr\u00f6\u00dferen Gemeinschaft aus ihrer eigenen religi\u00f6sen Perspektive interpretieren, aber sie werden nicht sehen. Sie werden gegen die Gr\u00f6\u00dfere Gemeinschaft k\u00e4mpfen und darauf bestehen, dass die Menschheit sich selbst \u00fcberlassen wird, aber sie werden nicht verstehen, dass die Menschheit an einer neuen Schwelle steht und dass die Anwesenheit der Gr\u00f6\u00dferen Gemeinschaft die Entwicklung des Lebens in dieser Welt darstellt. Sie werden f\u00fcr die Aufrechterhaltung ihrer religi\u00f6sen Vorstellungen k\u00e4mpfen. Sie werden f\u00fcr die Aufrechterhaltung ihrer eigenen Selbstidentit\u00e4t, wie sie sie kennen, k\u00e4mpfen, ohne die M\u00f6glichkeit zu akzeptieren, dass es ein neues Panorama f\u00fcr Wachstum und Entwicklung gibt.<\/p>\n<p>Sie werden gegen diese Realit\u00e4t k\u00e4mpfen. Sie werden sie aus ihrer eigenen, zur\u00fcckgezogenen Position heraus sehen. Doch sie werden nicht verstehen, womit sie es zu tun haben. Auch werden sie nicht in der Lage sein zu sehen, obwohl sie schauen. Sie werden von Angst und Furcht beherrscht werden.<\/p>\n<p>Die dritte m\u00f6gliche Reaktion ist, sich der Gr\u00f6\u00dferen Gemeinschaft zuzuwenden, zu erkennen, dass sie eine Realit\u00e4t ist, zu erkennen, dass sie neu ist, zu erkennen, dass sie einen neuen Ansatz und ein neues Verst\u00e4ndnis braucht und erfordert. Es wird einige wenige Menschen auf der Welt geben, die sie erkennen und einen aufrichtigen Versuch unternehmen werden, ihre Bedeutung zu verstehen. Wenn sie erfolgreich sein k\u00f6nnen, wenn sie den Weg der Kenntnis der Gr\u00f6\u00dferen Gemeinschaft lernen k\u00f6nnen, werden sie in der Lage sein, andere zu erziehen und anzuleiten und sie werden selbst eine positive Kraft f\u00fcr den Fortschritt in der Welt sein.<\/p>\n<p>Doch auch sie stehen vor gro\u00dfen Schwierigkeiten, aber sie m\u00fcssen lernen, die Situation mit neuen Augen und mit einem neuen Verst\u00e4ndnis zu sehen. Sie m\u00fcssen ihre Wahrnehmung und ihr Urteilsverm\u00f6gen entwickeln. Sie m\u00fcssen f\u00e4hig sein, das Leben in der Gr\u00f6\u00dferen Gemeinschaft kennen zu lernen, den Sinn und die Absicht der Besucher zu verstehen. Sie m\u00fcssen die F\u00e4higkeit haben, zu sehen, dass die Besucher keine Engel und keine D\u00e4monen sind, sondern echte f\u00fchlende Wesen wie sie selbst. Sie m\u00fcssen sich \u00fcber die Gegens\u00e4tzlichkeit von Gut und B\u00f6se hinaus bewegen, um klar und objektiv zu sehen.<\/p>\n<p>Sie werden auch mit der enormen Leugnung, die es geben wird und der Angst und Feindseligkeit, die \u00fcberall um sie herum existieren werden, zu k\u00e4mpfen haben. Entweder werden die Menschen es nicht wissen wollen oder sie werden die Dinge nur \u00e4ngstlich und abwehrend sehen. Sie werden sich mit diesen vorherrschenden Einstellungen und \u00dcberzeugungen auseinandersetzen m\u00fcssen, die in gewisser Weise ein noch gr\u00f6\u00dferes Hindernis darstellen werden als die Anwesenheit der Gr\u00f6\u00dferen Gemeinschaft selbst.<\/p>\n<p>Sie werden lernen m\u00fcssen, zwischen dem, was sie glauben und dem, was sie wissen, zu unterscheiden. Sie werden den Aberglauben erkennen m\u00fcssen, der sogar in ihrem eigenen Denken und ihren eigenen Bewertungen existiert. Ihr Lernbedarf wird enorm sein und doch werden sie eine Gelegenheit zur Entdeckung, zur Kreativit\u00e4t, zur Anpassung haben, die niemand sonst um sie herum haben wird.<\/p>\n<p>Daher gibt es drei m\u00f6gliche Reaktionen auf die Gr\u00f6\u00dfere Gemeinschaft. Es sind die gleichen drei m\u00f6glichen Reaktionen, die man auf jede neue Erfahrung im Leben haben kann. Dies sind die drei M\u00f6glichkeiten, die jeder haben kann, um Schwierigkeiten oder Widrigkeiten im Leben zu begegnen.<\/p>\n<p>Die Anwesenheit der Gr\u00f6\u00dferen Gemeinschaft bedeutet Schwierigkeiten, Widrigkeiten und Chancen. Doch wer ist in der Lage, dies zu erkennen? Wer kann das erkennen? Wer kann die Dinge sehen, wie sie wirklich sind? Wer hat den Mut, zu schauen? Wer hat die F\u00e4higkeit, den Unterschied zwischen Realit\u00e4t und eigener Wahrnehmung zu erkennen? Wer hat die Geduld und Ausdauer, einen Weg der Kenntnis der Gr\u00f6\u00dferen Gemeinschaft zu erlernen?<\/p>\n<p>Es gibt sehr m\u00e4chtige Kr\u00e4fte in der Welt, die die Menschheit in einem Zustand der Unwissenheit halten. In einigen F\u00e4llen versuchen sie, dies absichtlich zu tun. In anderen F\u00e4llen tun sie dies unbeabsichtigt, weil sie unwissend sind.<\/p>\n<p>Die Regierungen in der Welt versuchen, ihre Bev\u00f6lkerung gehorsam und gef\u00fcgig zu halten. Dies geschieht absichtlich. Sie glauben, dass es an ihnen liegt, die Probleme der gro\u00dfen Schwellen zu l\u00f6sen und dass die durchschnittliche Person nicht daf\u00fcr ausger\u00fcstet oder in der Lage ist, dies zu tun. Sie geben sich selbst die alleinige Autorit\u00e4t und Verantwortung, um die gro\u00dfen Probleme der Menschheit zu l\u00f6sen. Aber wie k\u00f6nnen sie das ohne den Willen der Bev\u00f6lkerung tun? Sie glauben nicht an Kenntnis. Sie glauben nur an \u00dcberredung und Manipulation.<\/p>\n<p>Die religi\u00f6sen Institutionen in der heutigen Welt wollen ihren urspr\u00fcnglichen Glauben bewahren. Sie wollen ihre Autorit\u00e4t bewahren. Sie wollen eine traditionelle Interpretation von G\u00f6ttlichkeit und Zweck und Bestimmung des Menschen bewahren.<\/p>\n<p>F\u00fcr sie stellt die Gr\u00f6\u00dfere Gemeinschaft eine solche Herausforderung und eine solche Bedrohung dar, dass sie anf\u00e4lliger daf\u00fcr sind, sie vollst\u00e4ndig zu leugnen. Und wenn sie sich dessen bewusst werden und in der Lage sind, sie weise zu interpretieren, werden sie dann den Mut und die Integrit\u00e4t haben, die Menschen zu erziehen, ihre Anh\u00e4nger und ihre Gemeinden zu erziehen?<\/p>\n<p>Das sind sehr ernste Fragen. Die Antwort darauf kann man finden, indem man in sich selbst hineinschaut, auf seine eigenen Tendenzen, auf seine eigenen \u00dcberzeugungen. Alle Tendenzen, von denen Ich bislang gesprochen habe, existieren in euch, weil ihr die Dinge in eurem Leben in der Vergangenheit geleugnet habt. Ihr habt gegen Ver\u00e4nderungen und Widrigkeiten gek\u00e4mpft. Und manchmal seid ihr auf etwas zugegangen, das neu war und einen neuen Ansatz erforderte.<\/p>\n<p>Ihr, die ihr dieses Buch lest, habt alle drei dieser m\u00f6glichen Reaktionen an den Tag gelegt. Selbst w\u00e4hrend der Lekt\u00fcre dieses Buches, selbst wenn ihr euch der Herausforderung und der Chance stellt, die Wir hier pr\u00e4sentieren, k\u00f6nnt ihr diese Tendenzen in euch selbst sp\u00fcren. Sie sind \u00fcberall. Und ihr werdet sie ganz sicher in den Menschen, die ihr kennt und in der Grundhaltung, dem Schwerpunkt und den Priorit\u00e4ten der \u00d6ffentlichkeit um euch herum sehen.<\/p>\n<p>Lest eure Zeitungen. Ihr werdet sehen, worin die menschlichen Priorit\u00e4ten liegen. Die Menschen sind fasziniert von Mord und Chaos, aber sie wollen sich nicht mit den gr\u00f6\u00dferen Ereignissen des Lebens auseinandersetzen. Sie wollen sich nicht mit der Tatsache auseinandersetzen, dass das Nahrungsangebot in der Welt abnimmt, dass die Ackerb\u00f6den abnehmen, dass die Umweltsysteme zusammenbrechen, dass es immer weniger Chancen und immer gr\u00f6\u00dfere Widrigkeiten im Leben gibt.<\/p>\n<p>Sie wollen nicht einmal die M\u00f6glichkeit anerkennen, dass es die Gr\u00f6\u00dfere Gemeinschaft in der Welt gibt. Vielleicht werden sie denken: &#8220;Nun, wir brauchen nicht noch so ein Problem!&#8221; Es gibt hier eine grundlegende Unf\u00e4higkeit, das Leben so zu sehen, wie es wirklich ist und zu unterscheiden zwischen dem, was ein kleines Problem ist und dem, was ein gro\u00dfes Problem ist. Diese Unf\u00e4higkeit wird von den m\u00e4chtigen Institutionen in der heutigen Welt unterst\u00fctzt.<\/p>\n<p>Nur durch das mutige Handeln von Einzelpersonen und kleinen Gruppen hat die Menschheit die Hoffnung, mit den sich wandelnden Umst\u00e4nden Schritt zu halten. Es muss mehr von diesen Individuen geben. [Dies] kann nicht einfach die Verantwortung von ein oder zwei begnadeten Menschen hier und da sein. Das Bed\u00fcrfnis nach Erziehung muss in jedem Menschen sp\u00fcrbar sein. Ihr d\u00fcrft euch nicht allein auf eure Institutionen verlassen, denn sie sind vielleicht nicht bereit oder nicht in der Lage, die gr\u00f6\u00dfere Erziehung bereitzustellen, die ihr braucht. Es liegt in eurer Verantwortung. Es ist eure Reaktion.<\/p>\n<p>Wenn ihr euch von der Zukunft abwendet, wird sie euch einholen. Wenn ihr die Zukunft bek\u00e4mpft, wird sie euch besiegen. Doch wenn ihr euch auf die Zukunft zubewegt und euch auf die Zukunft vorbereiten k\u00f6nnt, dann werdet ihr nicht nur in der Lage sein, direkt mit ihr umzugehen, sondern sie auch zu nutzen, um f\u00fcr euch selbst und f\u00fcr andere n\u00fctzliche Ergebnisse zu erzielen. Das ist es, was jetzt notwendig ist.<\/p>\n<p>Ihr habt eine starke Natur und eine schwache Natur in euch. Eure starke Natur wird durch die Realit\u00e4t der Kenntnis in euch verk\u00f6rpert. Eure schwache Natur ist eure Neigung, ohne Kenntnis zu leben und euch auf eure eigenen Vorstellungen und Vorlieben zu verlassen, um euch zu leiten. Hier m\u00fcsst ihr euch entscheiden, nicht nur einmal, sondern immer wieder, eure gr\u00f6\u00dfere Natur zu finden und zu beanspruchen und die gr\u00f6\u00dfere Macht und Verantwortung zu empfangen, die euch dies gibt.<\/p>\n<p>Wenn ihr versucht, zu entkommen und in einer Welt der Phantasie zu leben, in der ihr eure ganze Aufmerksamkeit auf eure Beziehungen, eure Hobbys oder eure pers\u00f6nlichen Zielen richtet, werdet ihr nicht in der Lage sein, zum Leben beizutragen und das Leben wird euch als gro\u00dfe Widrigkeit erscheinen.<\/p>\n<p>Wenn ihr gegen den Wandel und neue Offenbarungen k\u00e4mpft, werdet ihr gegen euch selbst k\u00e4mpfen, denn Kenntnis in euch versucht, euch in die Zukunft zu bringen, indem sie euch bef\u00e4higt, euch auf eine echte und produktive Weise mit der Gegenwart auseinanderzusetzen. Doch wenn ihr an euren Vorstellungen festhaltet, wenn ihr an euren \u00dcberzeugungen und Assoziationen festhaltet, werdet ihr nicht in der Lage sein, auf Kenntnis zu reagieren. Das Leben wird f\u00fcr euch wie ein Schlachtfeld werden und Gl\u00fcck, Frieden und Gleichmut werden euch unbekannt sein.<\/p>\n<p>Es gibt noch ein anderes Problem. Das ist das Problem des Einflusses. Das ist das Problem des Mangels der Menschheit an F\u00e4higkeiten und Bewusstsein in der mentalen Umgebung. Heute versuchen die Wesenheiten der Gr\u00f6\u00dferen Gemeinschaft, sich in der Welt zu etablieren. Sie sind hier, um Ressourcen aus der Welt zu erlangen. Sie versuchen, Einfluss auf das menschliche Denken zu nehmen.<\/p>\n<p>Ein Teil ihrer Agenda ist es, die kl\u00fcgsten und am meisten freidenkenden Individuen, diejenigen, die vielleicht am wenigsten traditionell oder konventionell in ihrem Ansatz sind, zu vereinnahmen und sie zu beschwichtigen. Hier sehen Wir zum Beispiel eine spirituelle Betonung von Frieden und Harmonie und den R\u00fcckzug aus dem Leben. Und doch ist dies kein R\u00fcckzug ins Kloster oder in den Konvent, wo echte spirituelle Ausrichtung und Aktivit\u00e4t stattfindet. Vielmehr ist es eher ein R\u00fcckzug aus dem Leben selbst.<\/p>\n<p>Es gibt heute einige spirituelle Lehren in der Welt, die keine g\u00f6ttliche Quelle haben. Sie sind das Produkt der Intervention von Kr\u00e4ften der Gr\u00f6\u00dferen Gemeinschaft. Sie motivieren die Menschen, Gl\u00fcck und Trost jenseits aller Dinge zu suchen, indem sie sie in einen Prozess des R\u00fcckzugs aus dem Leben und des R\u00fcckzugs von sich selbst versetzen.<\/p>\n<p>W\u00e4hrend diese Lehren Erleuchtung, grenzenloses Gl\u00fcck, Gleichmut und ununterbrochene Freude versprechen, neutralisieren sie tats\u00e4chlich die tieferen Neigungen der betroffenen Menschen und versetzen sie in eine Lage, in der sie nicht sehen, nicht wissen und nicht nach Kenntnis handeln k\u00f6nnen. Ihre W\u00fcnsche, ihre Vorlieben, ihre Hoffnungen werden so verw\u00f6hnt, dass sie nichts anderes sehen oder wissen k\u00f6nnen.<\/p>\n<p>Es ist eine bemerkenswerte Sache, dass mit der immer schwieriger werdenden Welt, die nach einer L\u00f6sung ruft, nach einem positiven Handeln, nach einem Beitrag, so viele Menschen, die in der Lage sind, diese Dinge zu erf\u00fcllen, beschwichtigt und behindert werden. Sie ziehen sich in ihre kleinen D\u00f6rfer in den Bergen oder an den Strand zur\u00fcck. Sie gehen weg von allem und jedem, was ihnen unangenehm ist. Sie versuchen sich zu isolieren und sich in einer Welt ohne Sorgen, in einer Welt ohne Schwierigkeiten zu isolieren.<\/p>\n<p>Und doch fragen sie sich, weshalb es solche Drangsal in ihnen selbst gibt. Vielleicht wird ihnen beigebracht, dass es Teil ihrer spirituellen Entfaltung ist, wenn es in Wirklichkeit der Konflikt ist, den sie erfahren, der das Ergebnis der Unf\u00e4higkeit ist, sich auf das Leben in sich selbst oder das Leben in der Welt einzulassen. Sie leiden, aber ihr Leiden ist gerechtfertigt. Sie wollen ihre Macht an eine gr\u00f6\u00dfere Macht abgeben, aber sie haben nicht die Weisheit oder das Urteilsverm\u00f6gen, um zu wissen, wem sie sich selbst hingeben sollen oder was das wirklich bedeutet.<\/p>\n<p>Also geben sie alles auf, um gef\u00fchrt zu werden, aber sie wissen nicht, wer sie f\u00fchrt. Sie wollen von den Verantwortlichkeiten des Lebens frei sein. Sie wollen, dass jemand anderes die Entscheidungen f\u00fcr sie trifft. Sie denken, dass es der Weg ist, wie kleine Kinder zu sein, mitgenommen, an der Hand gef\u00fchrt zu werden, um das Leben zu leben und echt im Leben zu sein. Sie verlieren ihre Autorit\u00e4t. Sie verlieren die Verbindung zu ihrer Seele, w\u00e4hrend sie die ganze Zeit glauben, dass sie ein wirklich spirituelles Leben f\u00fchren.<\/p>\n<p>Sie sind nicht in der Lage, sich der Gr\u00f6\u00dferen Gemeinschaft zu stellen. Sie sind nicht in der Lage, die Gr\u00f6\u00dfere Gemeinschaft zu verstehen. Sie sind nicht in der Lage, ihre eigene Autorit\u00e4t auszu\u00fcben, um ihre eigene St\u00e4rke auszudr\u00fccken, ihre Vorlieben beiseite zu legen, ihr Gl\u00fcck zu riskieren, etwas Wesentliches und Notwendiges im Leben zu tun. Sie haben den Willen verloren, sich auf das Leben einzulassen. Sie haben ihre Autorit\u00e4t aufgegeben.<\/p>\n<p>Ich kann euch versichern, dass der Sch\u00f6pfer dies nicht will. Das ist nicht der Weg. Der Fokus des Sch\u00f6pfers und der Unsichtbaren ist es, die Menschen stark, verantwortlich und f\u00e4hig zu machen. Es geht nicht darum, irgendeine Art von spirituellem Wohlfahrtssystem zu erzeugen, in dem die Menschen hoffen und erwarten, dass ihnen alles zur Verf\u00fcgung gestellt wird.<\/p>\n<p>Ich kann euch versichern, dass die Kr\u00e4fte der Gr\u00f6\u00dferen Gemeinschaft, die mit der Menschheit interagieren, diese Tendenzen voll ausnutzen und sie zu ihrem eigenen Nutzen einsetzen werden. Sie werden diese Individuen erforschen. Sie werden ihre tieferen Tendenzen neutralisieren. Sie werden sich ihre Naivit\u00e4t zunutze machen. Und sie werden ihre guten Absichten lenken.<\/p>\n<p>Vielleicht denkt ihr an diesem Punkt: &#8220;Mein Gott! Ist das m\u00f6glich? Wie ist das m\u00f6glich?&#8221; Aber wenn man die mentale Umgebung versteht, wird man sehen, was f\u00fcr eine Chance das f\u00fcr die Besucher bedeutet und wie einfach es f\u00fcr sie ist, Nutzen daraus zu ziehen.<\/p>\n<p>Vertraut keiner spirituellen Lehre, die nicht eure Autorit\u00e4t betont, die nicht die Wiedererlangung der Kenntnis in euch hervorhebt, die euch nicht in die Welt ruft, um zu reagieren und zu handeln, um mitzuwirken, zu lernen und zu geben. Geht auf keine spirituelle Lehre ein,die euch eurer Verantwortung daf\u00fcr beraubt und die keine echte und praktische Weisheit in euch kultiviert.<\/p>\n<p>Das m\u00fcsst ihr selbst erkennen, wenn ihr zu den mutigen Menschen geh\u00f6ren wollt, die sich dem Leben stellen und sich auf das Leben einlassen wollen, die sich daf\u00fcr entscheiden werden, auf dem Weg der Kenntnis stark zu werden und die sich daf\u00fcr entscheiden werden, Weisheit zu entwickeln.<\/p>\n<p>Wie Wir sagten, sind es eher die Tendenzen der Menschheit als die Absichten der Besucher, die am schwierigsten und entmutigendsten zu behandeln sein werden. Denn es gibt eine Vorbereitung, um zu lernen, wie man die Anwesenheit der Gr\u00f6\u00dferen Gemeinschaft in der Welt interpretieren, sich mit ihr auseinandersetzen und sich auf sie einstellen kann. Sie ist nicht \u00fcberm\u00e4chtig. Sie ist nicht allm\u00e4chtig. Sie verl\u00e4sst sich auf die menschliche Schw\u00e4che, um sich zu etablieren.<\/p>\n<p>Aber wo menschliche St\u00e4rke entstehen kann, wird sie feststellen, dass die Menschheit mehr als nur ein Gegner sein wird und sie werden ihre Agenda anpassen und ihren Ansatz \u00e4ndern m\u00fcssen und sie wird lernen m\u00fcssen, die Rechte, Privilegien und die Herrschaft der menschlichen Existenz zu respektieren.<\/p>\n<p>Dennoch m\u00fcsst ihr euch ihren Respekt verdienen. Ihr m\u00fcsst eure F\u00e4higkeiten unter Beweis stellen. Ihr m\u00fcsst eure Grenzen festlegen. Ihr m\u00fcsst euer Urteilsverm\u00f6gen erlangen. Ihr m\u00fcsst eure Autorit\u00e4t aus\u00fcben. Selbst wenn du die einzige Person bist, die das tut, musst du es tun.<\/p>\n<p>Schau auf das Leben. Werde ein Sch\u00fcler der Kenntnis. Lass die gr\u00f6\u00dfere Macht in dir zum Vorschein kommen. Sie wird dich wiederbeleben. Sie wird dir Mut, St\u00e4rke und Ausdauer geben. Sie wird dich \u00fcber Entmutigung und Entt\u00e4uschung hinausheben. Sie wird dir das Licht des Lebens geben. Sie wird dir das geben, was der Sch\u00f6pfer von dir will und sie wird dich bef\u00e4higen, das zu tun, was der Sch\u00f6pfer von dir will. Sie wird dich bef\u00e4higen, dich \u00fcber den Nebel menschlicher Leugnung, menschlicher Zwiesp\u00e4ltigkeit und menschlicher Feindseligkeit zu erheben. Sie wird dich aus dem Bereich des Glaubens in den Bereich der Gewissheit, Weisheit und St\u00e4rke f\u00fchren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es wird einige Zeit dauern, bis sich die Menschen an diese Vorstellung von der Gr\u00f6\u00dferen Gemeinschaft gew\u00f6hnen k\u00f6nnen. Sie stellt eine so gro\u00dfe Schwelle, einen so enormen Wendepunkt f\u00fcr die Menschheit dar. Einige Menschen werden sich darauf zubewegen, andere werden sich davon abwenden, wieder andere werden sich gegen sie wenden. Das sind die drei m\u00f6glichen Reaktionen, die jeder Mensch auf neue Vorstellungen und neue Erfahrungen haben kann. Innerhalb jeder dieser drei m\u00f6glichen Reaktionen gibt es mehrere verschiedene Manifestationen. Schauen Wir uns nun an, was jede davon bedeutet und woher diese Reaktionen in der Person und in der menschlichen Gesellschaft selbst kommen.<\/p>\n<p>Die erste Reaktion auf die Gr\u00f6\u00dfere Gemeinschaft w\u00e4re, sich von ihr abzuwenden. Die Menschen haben eine bemerkenswerte Tendenz, Dinge zu leugnen\u2014Dinge zu leugnen, die immer gegenw\u00e4rtig sind, Dinge zu leugnen, die kritische Probleme in der Welt darstellen, Dinge zu leugnen, die chronische Schwierigkeiten sind, sich so zu verhalten, als ob sie nicht da w\u00e4ren oder vorzugeben, dass sie die Kontrolle \u00fcber etwas haben, wenn sie es eigentlich gar nicht haben.<\/p>\n<p>Weil die Gr\u00f6\u00dfere Gemeinschaft ein enormer Wandel in der Wahrnehmung und im Verst\u00e4ndnis darstellt und weil die Gr\u00f6\u00dfere Gemeinschaft einen solch enormen Wandel in der Wahrnehmung und im Verst\u00e4ndnis erfordert, wird es viel Leugnung geben. Viele Menschen werden einfach \u00fcberhaupt nicht daran denken wollen. Und obwohl die Beweise daf\u00fcr, dass in der Welt viele nicht erbetene Besuche vor sich gehen und dass viele dieser Besucher sich in menschliche Angelegenheiten einmischen, jeden Tag zunehmen, tun die Menschen so, als ob \u00fcberhaupt nichts passiert. Sie gehen ihren eigenen Angelegenheiten nach, sind mit ihren eigenen pers\u00f6nlichen Angelegenheiten besch\u00e4ftigt. Sie werden einfach nicht zulassen, dass dies in ihr Bewusstsein kommt.<\/p>\n<p>Diese Art der Leugnung ist in der Welt sehr verbreitet. Die Menschen wollen es nicht wissen. Wieso ist das so? Woher kommt das? Warum gibt es diese Tendenz bei Menschen in so hohem Ma\u00dfe?<\/p>\n<p>Da sich die Menschheit in einem sehr fr\u00fchen Stadium ihrer Entwicklung befindet, besteht bei ihr eine F\u00fclle von Idealen und Aberglauben, die nichts mit der Realit\u00e4t zu tun haben. Stattdessen stellen sie die W\u00fcnsche und \u00c4ngste des menschlichen Bewusstseins dar. Diese k\u00f6nnen so stark ausgepr\u00e4gt sein, dass es f\u00fcr die Menschen sehr schwierig sein kann, etwas Neues zu h\u00f6ren. Es kann f\u00fcr sie sehr schwierig sein, klar zu sehen und klar zu verstehen, was in diesem Buch dargestellt wird.<\/p>\n<p>Wir verstehen diese Schwierigkeiten und Wir werden versuchen, die Realit\u00e4ten, die Wir pr\u00e4sentieren, so klar wie m\u00f6glich darzustellen. Allerdings m\u00fcsst ihr verstehen, dass ihr die Arbeit tun m\u00fcsst, um den Aussichtspunkt zu erlangen, von dem ihr selber sehen k\u00f6nnt. Es reicht nicht aus, einfach zu glauben was in diesem Buch dargestellt wird. Man muss es selbst erfahren und es klar sehen k\u00f6nnen. Dabei leistet ihr die meiste Arbeit.<\/p>\n<p>Wenn ihr in euren Sorgen versunken seid, wenn ihr in menschliche Ideale und \u00dcberzeugungen versunken seid, werdet ihr nicht in der Lage sein, das gr\u00f6\u00dfere Bild zu sehen und ihr werdet nicht in der Lage sein, die gr\u00f6\u00dferen Kr\u00e4fte zu erkennen, sowohl in euch selbst, als auch in der Welt rund um euch die euer Leben und eure Bestimmung formen. Deshalb bringen Wir mit unserer Botschaft eine gro\u00dfe Herausforderung. Wir wissen, wie gro\u00df sie ist.<\/p>\n","protected":false},"author":22,"featured_media":0,"parent":28940,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-leftsidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[76,1148,467],"tags":[1154,1155],"_links":{"self":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28982"}],"collection":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/comments?post=28982"}],"version-history":[{"count":1,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28982\/revisions"}],"predecessor-version":[{"id":28983,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28982\/revisions\/28983"}],"up":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28940"}],"wp:attachment":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/media?parent=28982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/categories?post=28982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/tags?post=28982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}