{"id":28532,"date":"2017-11-26T02:22:57","date_gmt":"2017-11-26T02:22:57","guid":{"rendered":"http:\/\/www.newmessage.org\/de\/?page_id=28532"},"modified":"2017-12-07T21:39:38","modified_gmt":"2017-12-07T21:39:38","slug":"das-aufstreben-der-menschheit-in-die-grosere-gemeinschaft","status":"publish","type":"page","link":"https:\/\/www.v6.newmessage.org\/de\/die-botschaft\/band-1\/die-grosere-gemeinschaft\/das-aufstreben-der-menschheit-in-die-grosere-gemeinschaft\/","title":{"rendered":"Das Aufstreben der Menschheit in die Gr\u00f6\u00dfere Gemeinschaft"},"content":{"rendered":"<div><!-- Version 3.5 --><\/div>\n<div class=\"tabgroup \"><ul class=\"tabs\"><li><a href=\"#tabs-1\">H\u00f6re<\/a><\/li>\n<li><a href=\"#tabs-2\"> Anmerkung<\/a><\/li><\/ul>\n <div id=\"tabs-1\"><\/p>\n<p>H\u00f6re die Stimme der Offenbarung:<\/p>\n\t\t\t\t<div id=\"jquery_jplayer_1\" class=\"jp-jplayer\"><\/div>\n\t\t\t\t<div id=\"jp_container_1\" class=\"jp-audio\">\n\t\t\t\t<div class=\"jp-type-single\"><div class=\"jp-control\"><a href=\"javascript:;\" class=\"jp-play\" tabindex=\"1\">play<\/a><a href=\"javascript:;\" class=\"jp-pause\" tabindex=\"1\">pause<\/a><\/div> <div class=\"jp-gui jp-interface\"><div class=\"jp-volume\"><div class=\"jp-volume-bar\"><div class=\"jp-volume-bar-value\"><\/div><\/div><\/div><div class=\"jp-progress\"><div class=\"jp-seek-bar\"><div class=\"jp-play-bar\"><\/div><\/div><\/div><\/div>\t\t\t\t\t<div class=\"jp-no-solution\"><span>Update Required<\/span>To play the media you will need to either update your browser to a recent version or update your <a href=\"http:\/\/get.adobe.com\/flashplayer\/\" target=\"_blank\">Flash plugin<\/a>.<\/div><\/div><\/div>\n\t\t\t<script type='text\/javascript'>\n\t\t\t\tjQuery(document).ready(function() {\n\t\t\t\t\tif (typeof (sermonMedia) == 'function') {\n\t\t\t\t\t\tsermonMedia.addAudio('', \"jquery_jplayer_1\");\n\t\t\t\t\t}\n\t\t\t\t\tjQuery.jPlayer.timeFormat.showHour = true;\n\t\t\t\t\tjQuery(\"#jquery_jplayer_1\").jPlayer({\n\t\t\t\t\t\tready: function(event) {\n\t\t\t\t\t\t\tjQuery(this).jPlayer(\"setMedia\", {mp3: 'https:\/\/www.newmessage.org\/av\/humanitys-emergence-into-the-greater-community.mp3'});\n\t\t\t\t\t\t},\n\t\t\t\t\t\tplay: function() {\n\t\t\t\t\t\t\tjQuery(this).jPlayer(\"pauseOthers\");\n\t\t\t\t\t\t},\n\t\t\t\t\t\tswfPath: ThemeData.directory_uri+\"\/swf\",\n\t\t\t\t\t\tsolution: \"html, flash\",\n\t\t\t\t\t\tpreload: \"metadata\",\n\t\t\t\t\t\twmode: \"window\",\n\t\t\t\t\t\tsupplied: \"mp3\",\n\t\t\t\t\t\tcssSelectorAncestor: '#jp_container_1'\n\t\t\t\t\t});\n\t\t\t\t});\n\t\t\t<\/script>\n<p><a title=\"Das Aufstreben der Menschheit in die Gr\u00f6\u00dfere Gemeinschaft\" href=\"https:\/\/www.newmessage.org\/av\/humanitys-emergence-into-the-greater-community.mp3\">Lade herunter<\/a> (Rechtsklick zum Herunterladen)<\/p>\n<p><em>Wie offenbart dem Boten<br \/>\nMarshall Vian Summers<br \/>\nam 18. Juli 2008 \u2013<br \/>\nin Boulder, Colorado<\/em><\/p>\n<p><\/div>\n<div id=\"tabs-2\"><br \/>\n<em> Anmerkung an den Leser:<br \/>\nDiese \u00dcbersetzung wurde der Society von einem Sch\u00fcler der Neuen Botschaft verf\u00fcgbar gemacht, der den englischen Originaltext als Freiwilliger \u00fcbersetzt hat. Wir stellen diese \u00dcbersetzung in dieser fr\u00fchen Form zur Verf\u00fcgung, damit jeder Gelegenheit hat, sich mit einem Teil der Neuen Botschaft in seiner eigenen Sprache zu befassen.<\/em><br \/>\n<\/div>\n\t\t\t\t<div align=\"right\">\n\t\t\t<div class=\"fb-like\" data-href=\"\" data-layout=\"button_count\" data-action=\"like\" data-show-faces=\"false\" data-share=\"false\"><\/div>\n\t\t\t<div class=\"fb-share-button\" data-layout=\"button_count\"> <\/div>\n\t\t\t<div class=\"fb_iframe_widget\"><a href=\"https:\/\/twitter.com\/godsnewmessage?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-show-count=\"false\">Follow @godsnewmessage<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n\t\t\t<\/div> <\/div> \n<br \/>\nDie Menschheit steht an der Schwelle zum All, an der Schwelle zur Gr\u00f6\u00dferen Gemeinschaft intelligenten Lebens im Universum. Obwohl es hier auf der Welt gro\u00dfe Probleme gibt und obwohl die Menschheit den Gro\u00dfen Wellen des Wandels, die auf die Welt zukommen, gegen\u00fcbersteht\u2014der Umweltzerst\u00f6rung; schwindenden Ressourcen; wachsender wirtschaftlicher und politischer Instabilit\u00e4t und dem Risiko von Wettbewerb, Konflikt und Krieg\u2014hat die Menschheit in ihrer Entwicklung eine gro\u00dfe Schwelle erreicht. Sie hat einen Punkt erreicht, an dem es keine R\u00fcckkehr in Bezug auf ihre Position in dieser Gr\u00f6\u00dferen Gemeinschaft des intelligenten Lebens gibt. <\/p>\n<p>Eure Isolation im Universum ist vorbei. Von diesem Punkt an werdet ihr mit verschiedenen Kr\u00e4ften k\u00e4mpfen m\u00fcssen, die zur Welt kommen, um hier Vorteile zu erlangen. <\/p>\n<p>Ihr lebt in einer wundersch\u00f6nen Welt mit herrlichen nat\u00fcrlichen Ressourcen. Aber eure Welt befindet sich in einem dicht besiedelten Teil des Universums, in dem es viele m\u00e4chtige technologische Gesellschaften gibt, die komplexe Handelsnetze gegr\u00fcndet haben.<\/p>\n<p>Diese Gesellschaften, wie so viele andere in der Gr\u00f6\u00dferen Gemeinschaft, haben die nat\u00fcrlichen Ressourcen ihrer Welten verbraucht, so dass sie nun sehr komplexe Vereinbarungen in Handel und Wirtschaft eingehen m\u00fcssen, um Zugang zu den Ressourcen zu erhalten, die sie ben\u00f6tigen. Ihr technologischer Fortschritt hat sie nicht von diesem Bed\u00fcrfnis befreit, sondern hat tats\u00e4chlich die Anforderungen des Lebens gesteigert.  <\/p>\n<p>Es gibt freie Gesellschaften in eurer Region des Weltraums, die nicht Teil dieser komplexen Handelsnetze sind und die in der Lage waren, die individuelle Freiheit und die Selbstbestimmung f\u00fcr ihre V\u00f6lker zu bewahren.<\/p>\n<p>Ihr strebt in ein komplexes Umfeld auf. Es \u00e4hnelt nicht dem, was die meisten Menschen von den M\u00f6glichkeiten des intelligenten Lebens im Universum glauben oder dar\u00fcber mutma\u00dfen.<br \/>\nViele Menschen glauben, dass das Universum ein gro\u00dfer leerer Ort ist und wenn Leben existiert, es dann selten ist. Viele Menschen glauben, dass, wenn die Menschheit einer anderen Rasse von Wesen im Universum begegnen w\u00fcrde, diese Rasse von Wesen \u00fcberm\u00e4\u00dfig an der Menschheit interessiert w\u00e4re, der Menschheit helfen und ihre Weisheit und Technologie mit dieser jungen aufstrebenden Rasse in der Welt teilen w\u00fcrde. <\/p>\n<p>Aber leider ist die Situation sehr unterschiedlich. Ihr befindet euch in einem sehr wettbewerbsstarken Umfeld, in dem Krieg und Konflikte selten sind, wo aber die Kr\u00e4fte von Einfluss und Manipulation stark sind. Ihr tretet in ein System von Umst\u00e4nden ein, das gut etabliert ist und seit langem etabliert wurde. <\/p>\n<p>Denn schlie\u00dflich streben Rassen im Universum Stabilit\u00e4t vor allem anderen an und diese Stabilit\u00e4t erfordert die Herstellung starker Beziehungen im Handel mit anderen Nationen, damit deren Konkurrenz dann nicht mehr destruktiv ist. Fortschrittliche Technologie erfordert viele Ressourcen und der Zugriff auf diese Ressourcen muss gesichert werden. Es werden also sehr langwierige Vorkehrungen getroffen und sehr wenig Abweichung oder Rebellion innerhalb dieser Netzwerke wird toleriert. <\/p>\n<p>Es ist, als ob die Menschheit ein kleines Kind w\u00e4re, das zum ersten Mal aus dem Haus geht und erkennt, dass es in einer gro\u00dfen Stadt lebt, die von starken Kr\u00e4ften gesteuert wird, die das kleine Kind nicht verstehen kann. Es unterscheidet sich sehr von den M\u00e4rchenb\u00fcchern, die das Kind gelesen hat oder von der Fantasie des Kindes. Es ist kein wunderbarer Ort, an dem alle gl\u00fccklich sind und jeder unterst\u00fctzt wird und sich alle gut verstehen. <\/p>\n<p>Die gr\u00f6\u00dfere Nachbarschaft des Lebens, in die ihr eintreten werdet und die Kr\u00e4fte, auf die ihr dort treffen k\u00f6nnt, sind nicht besonders an der Menschheit interessiert. Sie teilen nicht die Werte der Menschheit. Sie sind in den meisten F\u00e4llen nicht menschlich oder auch nur menschen\u00e4hnlich. Aber sie teilen die Schwierigkeiten, in einer physischen Realit\u00e4t zu leben\u2014die Schwierigkeiten der Sicherheit und der Sicherung von Ressourcen, die Schwierigkeiten des Wettbewerbs und all die innewohnenden Probleme, die sich der Zivilisation trotz ihrer vielen Vorteile stellen. <\/p>\n<p>Wie jeder in der Gr\u00f6\u00dferen Gemeinschaft m\u00fcsst ihr euch den Grenzen stellen, die das Leben und die Natur schafft. Die Technologie kann die meisten davon nicht \u00fcberwinden. So steht jeder vor den Problemen des \u00dcberlebens und der Sicherheit, der Konkurrenz und so weiter. <\/p>\n<p>Die Menschheit ist eine sehr junge Rasse. Sie ist in Technik vernarrt. Sie h\u00e4lt sie f\u00fcr au\u00dferordentlich wichtig im Universum. Sie glaubt und nimmt an, dass ihre Werte und ihre Bestrebungen universell sind. Das ist nat\u00fcrlich verst\u00e4ndlich, weil die Menschheit in dieser Gr\u00f6\u00dferen Gemeinschaft des Lebens niemals konkurrieren und \u00fcberleben musste. In eurer eigenen Welt isoliert, unf\u00e4hig, \u00fcber eure Grenzen hinweg zu reisen, kennt ihr nat\u00fcrlich die Realit\u00e4ten des Lebens in dieser weitaus gr\u00f6\u00dferen Arena nicht.<br \/>\nEs geht darum, die Menschheit \u00fcber die Realit\u00e4t und die Spiritualit\u00e4t der Gr\u00f6\u00dferen Gemeinschaft zu lehren, die einen der Hauptzwecke der Neuen Botschaft darstellt, die vom Sch\u00f6pfer allen Lebens in die Welt gesandt wurde. Denn nur Gott wei\u00df, was wirklich in der Gr\u00f6\u00dferen Gemeinschaft geschieht und wie sich die Menschheit selbst auf die Gro\u00dfen Wellen des Wandels vorbereiten muss, die auf die Welt zukommen und die jetzt auf euch zukommen. <\/p>\n<p>Die Verbindung zwischen den Gro\u00dfen Wellen des Wandels und dem Eintreten der Menschheit in diese Gr\u00f6\u00dfere Gemeinschaft des intelligenten Lebens ist sehr bedeutsam. Wie bei der Evolution so vieler Gesellschaften im Universum pl\u00fcndert die Menschheit nun die nat\u00fcrlichen Ressourcen ihrer Welt. Das bringt euch an eine gro\u00dfe Schwelle.<br \/>\nZuerst l\u00e4dt es die Intervention von Rassen ein, die diese biologischen Ressourcen f\u00fcr sich sichern m\u00f6chten. Sie werden alle notwendigen Mittel verwenden, um diesen Zugang zu erlangen, obwohl Gewalt in diesem Fall selten angewandt wird.<br \/>\nIhr habt auch die Schwelle erreicht, in der sich die Menschheit entscheiden muss\u2014sogar bewusst w\u00e4hlen wird\u2014ob sie \u00fcber diese verbleibenden Ressourcen in der Welt k\u00e4mpfen und ringen wird oder ob sie sich vereinigen wird, um sie zu erhalten und zu sichern und ein stabiles Umfeld f\u00fcr die Zukunft zu erlangen. <\/p>\n<p>Es ist an diesem Punkt, an dem so viele Welten von anderen kontaktiert werden, die ihnen Technologie und Ressourcen anbieten. Wenn die einheimischen V\u00f6lker die F\u00e4higkeit ihrer eigenen Selbstversorgung in der Welt ersch\u00f6pft haben, m\u00fcssen sie diese Angebote annehmen. Aber es sind diese Angebote, die die Einheimischen ihrer Selbstbestimmung, ihrer Freiheit und ihrer Selbstversorgung berauben werden. <\/p>\n<p>Wenn ihr einmal auf Handelsnetze im Universum angewiesen seid, bestimmen diese Netzwerke, wie ihr leben werdet und was ihr tun werdet. Ihr Einfluss auf euch wird \u00fcberm\u00e4\u00dfig sein, weil sie die Ressourcen kontrollieren werden, die f\u00fcr euer \u00dcberleben und Wohlbefinden unentbehrlich sind und auf die ihr euch verlassen m\u00fcsst. <\/p>\n<p>Es ist das Problem, die Selbstversorgung zu verlieren und von anderen abh\u00e4ngig zu werden. Wenn die Menschheit eine freie und selbstbestimmte Rasse im Universum werden soll, was eure gr\u00f6\u00dfere Bestimmung darstellt, d\u00fcrft ihr in dieser gr\u00f6\u00dferen Umgebung nicht eure Selbstversorgung verlieren.<br \/>\nDenn es gibt drei Voraussetzungen f\u00fcr eine Rasse, im Universum frei zu sein und besonders in den Regionen, die dicht besiedelt sind, wo Handelsnetze gut etabliert sind. Ihr m\u00fcsst vereint sein, ihr m\u00fcsst euch selbst versorgen und ihr m\u00fcsst \u00e4u\u00dferst diskret sein. <\/p>\n<p>Gegenw\u00e4rtig ist die Menschheit nicht geeint und l\u00e4uft Gefahr, immer geteilter und zerstrittener zu werden und einer Welt mit sinkenden Ressourcen zu begegnen.<br \/>\nMit jedem Tag verliert ihr eure Selbstversorgung, w\u00e4hrend ihr die F\u00fclle dieser Welt verbraucht, w\u00e4hrend ihr euer nat\u00fcrliches Erbe \u00fcberschreitet, w\u00e4hrend ihr r\u00fccksichtslos in die Zukunft treibt und immer mehr von einer Welt endlicher Ressourcen verbrauchen wollt.<br \/>\nIhr seid kaum diskret, da ihr eure St\u00e4rken und Schw\u00e4chen in das Universum sendet, damit es jeder sehen kann. Dies bedroht nat\u00fcrlich eure Zukunft und bedroht die M\u00f6glichkeit, in dieser gr\u00f6\u00dferen Arena des Lebens, in der Freiheit selten ist, Freiheit in der Zukunft zu sichern. <\/p>\n<p>Gro\u00dfe technologische Gesellschaften sind oft sehr weltlich. Sie erlauben keinen individuellen Ausdruck. Sie ehren nicht die Realit\u00e4t und die Pr\u00e4senz des Sch\u00f6pfers allen Lebens. Der Staat ist ihre Religion geworden und die Stabilit\u00e4t wird durch eine sehr strenge Hierarchie der Struktur aufrechterhalten. <\/p>\n<p>Dies ist der Fall bei Nationen, die sich gegenseitig auf Ressourcen verlassen. Sie werden einander immer \u00e4hnlicher, obwohl sie immer noch unterschiedliche Gesellschaften sind. Sie m\u00fcssen sich aufgrund ihrer gegenseitigen Abh\u00e4ngigkeit bis zu einem gewissen Grad anpassen.<br \/>\nDas ist der Grund, warum freie Nationen in Regionen des Weltraums, in denen eure Welt existiert, gr\u00f6\u00dftenteils unabh\u00e4ngig bleiben oder nur in begrenztem Ma\u00dfe miteinander handeln werden. Sie werden versuchen, sehr diskret zu sein, denn freie Gesellschaften koexistieren nicht gut mit denen, die nicht [frei] im Universum sind. <\/p>\n<p>Diese Erziehung \u00fcber die Gr\u00f6\u00dfere Gemeinschaft ist wesentlich, denn ihr m\u00fcsst ein Gesp\u00fcr daf\u00fcr haben, worauf ihr euch vorbereitet und ihr m\u00fcsst anfangen, eure eigene Verantwortung hier auf der Erde zu verwirklichen. Ihr tretet in eine gr\u00f6\u00dfere Arena des Lebens ein. Es ist keine Arena, die ihr in irgendeiner Weise kontrollieren oder gar beeinflussen werdet. Ihr tretet aus der Isolation heraus.<br \/>\nRassen aus der Gr\u00f6\u00dferen Gemeinschaft sind bereits hier und mischen sich in menschliche Angelegenheiten ein\u2014versuchen sich als Zentren der Macht und des Einflusses hier zu etablieren, operieren heimlich hinter den Kulissen, beeinflussen Menschen in Machtpositionen, entf\u00fchren B\u00fcrger gegen ihren Willen und agieren in einer Weise, die h\u00f6chst gef\u00e4hrlich und gefahrvoll f\u00fcr die menschliche Familie ist. <\/p>\n<p>Doch die Menschen gehen ihrem Leben nach, als ob nichts geschieht, verzehrt von ihren eigenen Bed\u00fcrfnissen, verzehrt von menschlichem Konflikt und Korruption, verzehrt von den Schwierigkeiten des Lebens hier in dieser einen Welt, unbewusst und unbek\u00fcmmert \u00fcber die bestehende Intervention hier. Die wenigen Menschen, die sich dieser Anwesenheit bewusst sind, werden \u00fcberredet, sie als vorteilhaft, als gutartig und in manchen F\u00e4llen sogar als Rettung f\u00fcr die menschliche Familie anzusehen. <\/p>\n<p>Angesichts einer Welt mit r\u00fcckl\u00e4ufigen Ressourcen und wachsender Instabilit\u00e4t ist die Menschheit besonders anf\u00e4llig f\u00fcr \u00dcberredung und Intervention. Daf\u00fcr gibt es viele Gr\u00fcnde. Aber die Realit\u00e4t ist, dass die Menschheit ihrer gr\u00f6\u00dfter Herausforderung von au\u00dfen begegnet und nicht reagiert. <\/p>\n<p>Nat\u00fcrlich gibt es Einzelpersonen und Regierungen in eurer Welt, die sich dessen bewusst sind, aber die breite \u00d6ffentlichkeit hat keine Ahnung von den Gefahren, denen sie an ihren Grenzen gegen\u00fcber dem Weltraum ausgesetzt ist. Das sind Gefahren, denen sich die Menschheit stellen und sie \u00fcberwinden kann, aber damit dies m\u00f6glich ist, muss sie sich vereinen und daf\u00fcr ausgebildet werden. <\/p>\n<p>Diese Rassen, die heutzutage hier in der Welt sind, verlassen sich ganz auf die menschliche Duldung und Unterwerfung. Sie wenden keine Gewalt an, um ihre Ziele zu erreichen. Wenn die Menschheit diese Erlaubnis nicht gibt, sie nicht akzeptiert und sich nicht unterwirft, dann m\u00fcssen sich diese Kr\u00e4fte zur\u00fcckziehen. <\/p>\n<p>Die Neue Botschaft f\u00fcr die Menschheit erkl\u00e4rt, warum dies der Fall ist, aber dies erfordert, dass ihr dies untersucht und \u00fcber die Realit\u00e4t des Lebens jenseits der Grenzen dieser Welt aufgekl\u00e4rt werdet. Ihr d\u00fcrft keine wilden Annahmen treffen oder an alten Vorstellungen oder Meinungen festhalten und die Hoffnung haben, diese Erziehung und dieses Verst\u00e4ndnis zu erlangen. Wie k\u00f6nntet ihr das wissen? Wie k\u00f6nnte irgendjemand auf der Welt wissen, was in der Gr\u00f6\u00dferen Gemeinschaft des Lebens um euch herum geschieht? <\/p>\n<p>Dies muss euch mit einer gr\u00f6\u00dferen Offenbarung bereitgestellt werden. W\u00e4hrend ihr Verb\u00fcndete im Universum habt, die euch ihre Lageberichte, ihre Weisheit und ihre Empfehlungen gesandt haben, muss diese Offenbarung wirklich vom Sch\u00f6pfer allen Lebens kommen. Diese Offenbarung muss f\u00fcr das Wohlergehen der Menschheit kommen. Sie wurde vorher nie in der Welt gebraucht, aber sie ist jetzt notwendig. <\/p>\n<p>Die Menschheit kann sich nicht selbst auf eine Gr\u00f6\u00dfere Gemeinschaft, die sie nicht verstehen kann, vorbereiten. Sie kann sich nicht auf ein System von Umst\u00e4nden vorbereiten, das sie nicht bezeugen kann. Doch diese Vorbereitung ist heute in der Welt von entscheidender Bedeutung. <\/p>\n<p>Ihr habt gro\u00dfe Barrieren und gro\u00dfe Mauern zwischen euren Nationen. Ihr habt immense Defensiv- und Offensivpotentiale zwischen euren Nationen aufgebaut. Aber ihr steht mit dem R\u00fccken zum Universum. Aber ihr seid nicht aufmerksam. Ihr bringt hier keine Weisheit zum Tragen\u2014wenn ihr die Lehren aus der eigenen Geschichte lernt und erkennt, k\u00f6nnt ihr verstehen, dass dieser Wettbewerb Teil der Natur ist und dass das Universum die Natur in einem gr\u00f6\u00dferen und fast unverst\u00e4ndlichen Ma\u00dfstab repr\u00e4sentiert. <\/p>\n<p>Der Sch\u00f6pfer allen Lebens hat euch Kenntnis gegeben, eine tiefere Intelligenz in euch. Sie repr\u00e4sentiert eure F\u00e4higkeit, die Wahrheit jenseits jeder T\u00e4uschung zu erkennen, jenseits jeder Vorliebe, jenseits von Hoffnung, jenseits von Angst, jenseits all der vielen Dinge, die die Sicht und das Verst\u00e4ndnis der Menschheit tr\u00fcben. <\/p>\n<p>Du bist in die Welt gekommen, um der Welt unter diesen Umst\u00e4nden zu dienen. Du bist nicht zuf\u00e4llig hier. Was dich wirklich in die Welt gebracht hat, h\u00e4ngt mit dem Aufstreben der Menschheit in die Gr\u00f6\u00dfere Gemeinschaft und mit den gro\u00dfen Schwierigkeiten zusammen, mit denen die Menschheit hier auf der Erde infolge ihres Missbrauchs und der \u00dcberbeanspruchung der Welt konfrontiert sein wird. <\/p>\n<p>Das ist das gro\u00dfe Bild eures Lebens. Es repr\u00e4sentiert die Realit\u00e4t der Existenz der Menschheit und die gro\u00dfe Schwelle, der die Menschheit jetzt gegen\u00fcbersteht. Doch wer denkt an diese Dinge? Wer kann hier deutlich sehen? Wer kann den gesunden Menschenverstand f\u00fcr ein ganz anderes und neues System von Umst\u00e4nden einsetzen? Wer hat die Objektivit\u00e4t, Herausforderungen dieser Art zu begegnen, ohne eigene \u00c4ngste, Vorlieben und Leugnungen darauf zu projizieren? <\/p>\n<p>Die Menschheit kann in diesem Moment kaum noch ihren eigenen Schwierigkeiten hier auf der Erde mit einem Grad an Klarheit und Vision begegnen. Wie wird sie einer Gr\u00f6\u00dferen Gemeinschaft des Lebens gegen\u00fcberstehen? Wo wird sie die St\u00e4rke finden, sich angesichts dieser Gr\u00f6\u00dferen Gemeinschaft zu vereinigen und sich als freie und selbstbestimmte Rasse innerhalb dieser gr\u00f6\u00dferen Arena des Lebens zu etablieren? <\/p>\n<p>Das sind Fragen, die ihr wirklich nicht beantworten k\u00f6nnt, denn ihr braucht die Macht und die Gnade des Sch\u00f6pfers allen Lebens, euch zu unterweisen und euch vorzubereiten. Ihr k\u00f6nnt euch nicht selbst darauf vorbereiten. Ihr wisst nicht einmal, worauf ihr euch vorbereiten sollt oder was die Vorbereitung erfordert und wie ihr in der Lage sein werdet, eine gr\u00f6\u00dfere Stabilit\u00e4t in der Welt zu erreichen und die Ressourcen der Welt zu bewahren, damit eure Freiheit in der Zukunft hier eine Grundlage haben kann. <\/p>\n<p>Die Menschen werden die Hoffnung angesichts der Gro\u00dfen Wellen des Wandels verlieren. Sie werden die Hoffnung und das Selbstvertrauen im Angesicht der Gr\u00f6\u00dferen Gemeinschaft verlieren. Sie werden die Hoffnung verlieren, nicht weil sie nicht die St\u00e4rke haben, sondern weil sie nicht erkennen, dass sie die St\u00e4rke haben, sich diesen gro\u00dfen und gewaltigen Hindernissen zu stellen, denen alle Rassen im Leben fr\u00fcher oder sp\u00e4ter begegnen werden. <\/p>\n<p>Die Menschheit hat die M\u00f6glichkeit zur Selbsterkenntnis. Sie hat in ausreichendem Ma\u00dfe das Bewu\u00dftsein des Sch\u00f6pfers allen Lebens, um eine gr\u00f6\u00dfere innere Kraft anzustreben. Sie hat die Lehren der Natur in dieser Welt ausreichend gelernt, um diese Weisheit in ihrer Begegnung mit einer Gr\u00f6\u00dferen Gemeinschaft zum Tragen zu bringen. <\/p>\n<p>Aber es gibt Dinge, die die Menschheit nicht sehen und nicht wissen kann, wie das Leben jenseits ihrer Grenzen ist\u2014wie diese Gr\u00f6\u00dfere Gemeinschaft wirklich ist, wie sie funktioniert und wie eine Rasse wie eure eigene sich dieser [Realit\u00e4t] ann\u00e4hern muss, um die Freiheit und Souver\u00e4nit\u00e4t in dieser Welt, zu sichern. <\/p>\n<p>Ihr kennt hier noch nicht eure M\u00f6glichkeiten und die Gefahren, die euch umgeben. Niemand in der Welt ist \u00fcber die Gr\u00f6\u00dfere Gemeinschaft informiert. Wenn sie das w\u00e4ren, w\u00fcrden sie sehr unterschiedlich auf die Anwesenheit extraterrestrischer M\u00e4chte in eurer Mitte reagieren. Dies w\u00fcrde ein weltweiter Schwerpunkt werden und der Schwerpunkt w\u00fcrde darauf liegen, eure eigenen Regeln f\u00fcr den Kontakt festzulegen, wem auch immer ihr jetzt begegnet und wahrscheinlich in der Zukunft begegnen werdet.<br \/>\nIhr w\u00fcrdet eure Kriege und eure Konflikte beenden und erkennen, wie verletzlich sie euch gegen\u00fcber \u00e4u\u00dferem Einfluss und Manipulation machen. Ihr w\u00fcrdet eine gr\u00f6\u00dfere N\u00fcchternheit und Sachlichkeit an den Tag legen, um jene Kr\u00e4fte, die in der Welt sind, zu erkennen und um ihrem Verhalten hier entgegenzuwirken. Ihr w\u00fcrdet erkennen, dass alles, was ihr jetzt habt, in Gefahr ist\u2014alles, was die Menschheit erreicht hat, das vorteilhaft ist, alles, was die Menschheit geschaffen hat, jetzt in Gefahr ist.<\/p>\n<p>Ihr steht vor einer Reihe von Einfl\u00fcssen, die darauf abzielen, euch nicht zu zerst\u00f6ren, sondern euch zu gebrauchen, um euch im Dienst f\u00fcr sie einzusetzen. Es ist an der Zeit, die unaufh\u00f6rlichen Konflikte zu beenden und euch auf die Gr\u00f6\u00dfere Gemeinschaft des intelligenten Lebens vorzubereiten. Das ist weitaus wichtiger als Streitfragen, die ihr untereinander habt. Eure Spaltungen, eure Konkurrenz, eure Konflikte und eure mangelnde Bereitschaft, eure Nationen gegenseitig zu unterst\u00fctzen, machen euch angesichts dieser Gr\u00f6\u00dferen Gemeinschaft nur schwach und verletzlich. <\/p>\n<p>Eure wenigen Verb\u00fcndeten im Universum, die sich eurer Existenz bewusst sind, jene Rassen, die in eurer Nachbarschaft im All leben, die ein gewisses Ma\u00df an Selbstversorgung und Selbstbestimmung erreicht haben, haben euch eine Reihe von Lageberichten gesandt, um euch vor den au\u00dferirdischen Kr\u00e4ften zu warnen, die heute in der Welt sind und um euch zu helfen, sich auf die Realit\u00e4ten des Lebens innerhalb der Gr\u00f6\u00dferen Gemeinschaft selbst vorzubereiten. <\/p>\n<p>Sie wurden vom Sch\u00f6pfer allen Lebens aufgefordert, dies zu bezeugen, denn die Menschheit muss wissen, dass sie eventuell Freunde im Universum hat. Sie sind heute nicht in der Welt. Sie mischen sich nicht in menschliche Angelegenheiten ein. Sie beobachten euch von weitem. Sie wissen, dass die wirkliche Vorbereitung vom Sch\u00f6pfer allen Lebens kommen muss, denn nur der Sch\u00f6pfer allen Lebens wei\u00df alles \u00fcber die Gr\u00f6\u00dfere Gemeinschaft und alles, was die Menschheit wissen, tun und nicht tun muss, um sich auf diese Gr\u00f6\u00dfere Gemeinschaft vorzubereiten. <\/p>\n<p>Der Sch\u00f6pfer allen Lebens hat euch Kenntnis und Weisheit aus dieser Gr\u00f6\u00dferen Gemeinschaft gebracht und hat eine Warnung, einen Segen und eine Vorbereitung in die Welt gesandt. Sie ist hier, um die Menschheit auf das gr\u00f6\u00dfte Ereignis in der Geschichte der Menschheit vorzubereiten, die gr\u00f6\u00dfte Bedrohung f\u00fcr die menschliche Freiheit und Selbstbestimmung und die gr\u00f6\u00dfte Chance f\u00fcr menschliche Einheit und Zusammenarbeit. <\/p>\n<p>Warum w\u00fcrde eine Nation hier in der Welt mit anderen Nationen k\u00e4mpfen, wenn sie erkennen w\u00fcrde, dass ihre gesamte Zukunft und ihre Realit\u00e4t durch die Konkurrenz von au\u00dferhalb dieser Welt herausgefordert w\u00e4re? Wer w\u00e4re t\u00f6richt genug, die Menschheit in einen Konflikt zu st\u00fcrzen, wenn sie die gr\u00f6\u00dfere Herausforderung, vor der die gesamte menschliche Familie steht, kennen und verstehen w\u00fcrde? <\/p>\n<p>Die Gr\u00f6\u00dfere Gemeinschaft hat hier viele Vorteile f\u00fcr euch. Sie ist das eine, das die Menschheit vereinen und ihre unaufh\u00f6rlichen Konflikte beenden kann. Sie ist das eine, das euch zwingen kann, zu reifen, euch zu vereinen und zum Schutz eurer Welt zusammenzuarbeiten. Sie wird euch dazu zwingen, verantwortlich zu sein, wo ihr unverantwortlich seid. Sie wird euch zwingen, reif zu sein, wo ihr unreif seid. Sie wird euch zwingen, zu erkennen, dass ihr euch um diese Welt k\u00fcmmern m\u00fcsst, dass ihr hier eine nachhaltige Existenz schaffen m\u00fcsst und dass ihr nicht in das Universum gehen k\u00f6nnt, um zu fordern, was ihr hier in dieser Welt zerst\u00f6rt habt, denn diese Ressourcen geh\u00f6ren anderen und ihr werdet keine Macht oder wirksame Mittel haben, um Zugang zu ihnen zu erhalten. Und eure Freiheit und eure Selbstbestimmung in dieser gr\u00f6\u00dferen Arena des Lebens wird es erforderlich machen, dass die Menschheit autark und verantwortlich ist, um ihre eigenen L\u00f6sungen f\u00fcr schwierige Probleme hier auf der Erde zu finden. <\/p>\n<p>Die Menschheit ist immer noch wild und r\u00fccksichtslos. Wie ein Jugendlicher f\u00e4ngt sie an, ihre Macht zu f\u00fchlen, aber sie ist noch nicht verantwortlich. Sie ist noch nicht reif genug, um diese Macht zu ihrem eigenen Vorteil effektiv zu nutzen. Sie denkt nicht an ihre Zukunft und sie erkennt nicht die gro\u00dfen Risiken, mit denen sie in dieser Gr\u00f6\u00dferen Gemeinschaft konfrontiert ist. Sie hat noch nicht das Selbstvertrauen, die Reife oder die F\u00e4higkeit, sich diesem gr\u00f6\u00dferen Panorama des Lebens zu stellen. <\/p>\n<p>Das ist eure Herausforderung. Ihr k\u00f6nnt es nicht vermeiden. Es gibt keinen Ort, wohin man laufen und sich verstecken k\u00f6nnte. Werdet ihr euch in einer anderen Welt verstecken? Werdet ihr so tun als ob? Werdet ihr diese Realit\u00e4t leugnen? Denkt ihr, dass das irrelevant ist?<\/p>\n<p>Dies ist die gro\u00dfe Schwelle, die die Menschheit emporheben und vereinen kann. Es ist auch die gro\u00dfe Schwelle, die die Menschheit untergraben kann. Sie hat diese Macht und diese St\u00e4rke. Es ist euer Mut, euer Selbstvertrauen und eure Selbstbestimmung, die jetzt zum Tragen kommen m\u00fcssen.<br \/>\nTechnologie ist nicht euer Problem. Euer Problem hat mit Mut, Klarheit und Entschlossenheit zu tun. Ihr werdet nicht wegen der Technologie scheitern. Ihr werdet wegen des Mangels an Weisheit, Zusammenarbeit und Bewusstsein in eurer Welt scheitern. Das ist eure gro\u00dfe Gefahr.<br \/>\nIhr habt Macht. Ihr habt F\u00e4higkeiten. Ihr habt Weisheit. Niemand sonst kann in eurer Welt leben. Es ist biologisch zu komplex f\u00fcr sie. Sie brauchen euch. Sie brauchen eure Zusammenarbeit. Ihr m\u00fcsst euch ihnen bereitwillig unterwerfen. Sie m\u00fcssen euer Selbstvertrauen aush\u00f6hlen, damit ihr das Gef\u00fchl habt, dass ihr ihnen nicht widerstehen k\u00f6nnt. Sie wollen, dass ihr eure Ressourcen ersch\u00f6pft, damit ihr von ihnen abh\u00e4ngig werdet. <\/p>\n<p>Dies ist eine grundlegende Bildung. Doch Menschen haben viele Vorstellungen und \u00dcberzeugungen, die sie f\u00fcr die Realit\u00e4t ihrer Situation blind machen. Vorlieben, Leugnung, menschliche Konflikte, die Verschlechterung der Umwelt durch den Menschen\u2014all dies bringt euch in eine extreme Situation der Ohnmacht und der Verwundbarkeit im Universum. <\/p>\n<p>Was w\u00fcrde euch motivieren, euch zu \u00e4ndern? Es muss etwas sehr Starkes, sehr \u00dcberw\u00e4ltigendes sein, etwas, woran ihr vorher nicht gedacht hattet\u2014ein Dilemma, das gr\u00f6\u00dfer ist als alles, dem ihr glaubt, heute zu begegnen, einer Herausforderung aus dem Universum, die euch in eurer Verletzlichkeit und eurem System von Umst\u00e4nden erweckt. <\/p>\n<p>Das ist die gro\u00dfe Schwelle und ihr m\u00fcsst die St\u00e4rke, das Herz und den Mut haben, euch dem zu stellen und zu erkennen, dass ihr keine Antwort habt. Ihr k\u00f6nnt dies nicht selbst herausfinden. Ihr habt nicht alle notwendigen Informationen oder die notwendige Perspektive. Darum bringt der Sch\u00f6pfer allen Lebens diese Neue Offenbarung in die Welt\u2014um die Menschheit auf die Gro\u00dfen Wellen des Wandels vorzubereiten und die Menschheit auf die Realit\u00e4ten des Lebens in der Gr\u00f6\u00dferen Gemeinschaft vorzubereiten. <\/p>\n<p>Die Menschheit hat eine gro\u00dfe Bestimmung. Ihre Bestimmung ist es, eine freie und selbstbestimmte Rasse im Universum zu werden. Aber um diese Bestimmung zu erf\u00fcllen, m\u00fcsst ihr stark, geeint und entschlossen sein. Ihr m\u00fcsst erkennen, dass eure Isolation im Universum vorbei ist und dass ihr von nun an mit diesen Kr\u00e4ften zu k\u00e4mpfen habt, die versuchen werden, euch zu \u00fcberzeugen, dass ihr auf sie angewiesen seid, die versuchen werden, euer Selbstvertrauen zu untergraben, die versuchen werden, ihren Einfluss hier in der Welt zu etablieren\u2014in einer Welt, in der sie nicht leben k\u00f6nnen. <\/p>\n<p>Ihr werdet viele Fragen haben und es gibt Vieles, was ihr lernen m\u00fcsst. Die Offenbarung von Gott wird viele dieser Fragen beantworten. Aber das wird [Zeit] brauchen und erfordert, dass ihr heute Vieles in der Welt \u00fcberdenkt, dass ihr die Welt anders seht, dass ihr menschlichen Konflikt anders betrachtet und dass ihr erkennt, dass eure Zukunft und eure Bestimmung, euer Erfolg und euer Scheitern in der Gr\u00f6\u00dferen Gemeinschaft selbst liegt. Wenn ihr das erkennen k\u00f6nnt, wird es ein gro\u00dfer Segen sein. Es wird eine Offenbarung sein. Es wird ein echter Wendepunkt f\u00fcr jeden von euch sein. <\/p>\n<p>Ihr werdet sehen, dass ihr eine gr\u00f6\u00dfere N\u00fcchternheit und Objektivit\u00e4t zum Tragen bringen m\u00fcsst und dass die St\u00e4rke, dies zu tun, in euch lebt\u2014eine tiefere St\u00e4rke, die St\u00e4rke der Kenntnis, die nur darauf wartet, entdeckt zu werden. Diese Kenntnis muss im Leben jedes Einzelnen hervortreten und muss in der menschlichen Familie st\u00e4rker werden. <\/p>\n<p>Das ist die Voraussetzung der Freiheit im Universum. Dies ist das Geschenk einer Gr\u00f6\u00dferen Gemeinschaft des Lebens. Dies ist die Gabe der Offenbarung an euch, die ihr jetzt an der Schwelle zum All steht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Menschheit steht an der Schwelle zum All, an der Schwelle zur Gr\u00f6\u00dferen Gemeinschaft intelligenten Lebens im Universum. Obwohl es hier auf der Welt gro\u00dfe Probleme gibt und obwohl die Menschheit den Gro\u00dfen Wellen des Wandels, die auf die Welt zukommen, gegen\u00fcbersteht\u2014der Umweltzerst\u00f6rung; schwindenden Ressourcen; wachsender wirtschaftlicher und politischer Instabilit\u00e4t und dem Risiko von Wettbewerb,\u2026 <a class=\"read-more\" href=\"https:\/\/www.v6.newmessage.org\/de\/about-recording-shortcode\/\"><span>Read More<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"parent":16486,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-leftsidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[110,76,118,30,464,460],"tags":[1051,742,1052,741],"_links":{"self":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28532"}],"collection":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/comments?post=28532"}],"version-history":[{"count":2,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28532\/revisions"}],"predecessor-version":[{"id":28543,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/28532\/revisions\/28543"}],"up":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/16486"}],"wp:attachment":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/media?parent=28532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/categories?post=28532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/tags?post=28532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}