{"id":27200,"date":"2017-04-27T08:33:11","date_gmt":"2017-04-27T08:33:11","guid":{"rendered":"http:\/\/www.newmessage.org\/german-international\/?page_id=27200"},"modified":"2019-06-27T04:25:32","modified_gmt":"2019-06-27T04:25:32","slug":"das-herz-gottes","status":"publish","type":"page","link":"https:\/\/www.v6.newmessage.org\/de\/die-botschaft\/band-1\/der-eine-gott\/das-herz-gottes\/","title":{"rendered":"Das Herz Gottes"},"content":{"rendered":"<div><!-- Master Archive version 4.1--><\/div>\n\n<div class=\"tabgroup \"><ul class=\"tabs\"><li><a href=\"#tabs-1\">H\u00f6re<\/a><\/li>\n<li><a href=\"#tabs-2\"> Anmerkung<\/a><\/li><\/ul>\n <div id=\"tabs-1\"><br \/>\nH\u00f6re die Stimme der Offenbarung:<\/p>\n<div id=\"jquery_jplayer_1\" class=\"jp-jplayer\"><\/div>\n\t\t\t\t<div id=\"jp_container_1\" class=\"jp-audio\">\n\t\t\t\t<div class=\"jp-type-single\"><div class=\"jp-control\"><a href=\"javascript:;\" class=\"jp-play\" tabindex=\"1\">play<\/a><a href=\"javascript:;\" class=\"jp-pause\" tabindex=\"1\">pause<\/a><\/div> <div class=\"jp-gui jp-interface\"><div class=\"jp-volume\"><div class=\"jp-volume-bar\"><div class=\"jp-volume-bar-value\"><\/div><\/div><\/div><div class=\"jp-progress\"><div class=\"jp-seek-bar\"><div class=\"jp-play-bar\"><\/div><\/div><\/div><\/div>\t\t\t\t\t<div class=\"jp-no-solution\"><span>Update Required<\/span>To play the media you will need to either update your browser to a recent version or update your <a href=\"http:\/\/get.adobe.com\/flashplayer\/\" target=\"_blank\">Flash plugin<\/a>.<\/div><\/div><\/div>\n\t\t\t<script type='text\/javascript'>\n\t\t\t\tjQuery(document).ready(function() {\n\t\t\t\t\tif (typeof (sermonMedia) == 'function') {\n\t\t\t\t\t\tsermonMedia.addAudio('', \"jquery_jplayer_1\");\n\t\t\t\t\t}\n\t\t\t\t\tjQuery.jPlayer.timeFormat.showHour = true;\n\t\t\t\t\tjQuery(\"#jquery_jplayer_1\").jPlayer({\n\t\t\t\t\t\tready: function(event) {\n\t\t\t\t\t\t\tjQuery(this).jPlayer(\"setMedia\", {mp3: 'https:\/\/newmessage.org\/av\/the-heart-of-god.mp3'});\n\t\t\t\t\t\t},\n\t\t\t\t\t\tplay: function() {\n\t\t\t\t\t\t\tjQuery(this).jPlayer(\"pauseOthers\");\n\t\t\t\t\t\t},\n\t\t\t\t\t\tswfPath: ThemeData.directory_uri+\"\/swf\",\n\t\t\t\t\t\tsolution: \"html, flash\",\n\t\t\t\t\t\tpreload: \"metadata\",\n\t\t\t\t\t\twmode: \"window\",\n\t\t\t\t\t\tsupplied: \"mp3\",\n\t\t\t\t\t\tcssSelectorAncestor: '#jp_container_1'\n\t\t\t\t\t});\n\t\t\t\t});\n\t\t\t<\/script><\/p>\n<p><a title=\"The Heart of God\" href=\"https:\/\/newmessage.org\/av\/the-heart-of-god.mp3\">Lade herunter<\/a> (Rechtsklick zum Herunterladen)<\/p>\n<p><em>Wie offenbart<br \/>\nMarshall Vian Summers<br \/>\nam 25. Januar 2015 \u2013<br \/>\nin Jerusalem, Israel <\/em><br \/>\n<div class=\"toggle toggle-white\"><h4 class=\"trigger \"><span class=\"t_ico\"><\/span><a href=\"#\">\u00dcber diese Aufzeichnung<\/a><\/h4><div class=\"toggle_container \"><br \/>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3327\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">Was Du in dieser Audioaufzeichnung h\u00f6rst, ist die Stimme des Engelsrates, die durch den Boten Marshall Vian Summers spricht.<\/span><\/span><\/div>\n<div dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">\u00a0<\/span><\/span><\/div>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3359\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\"> Hier wird die originale Mitteilung Gottes, die jenseits von Worten existiert, vom Engelsrat, der \u00fcber die Welt wacht, in menschliche Sprache und menschliches Verst\u00e4ndnis \u00fcbersetzt. Der Engelsrat bringt dann Gottes Botschaft \u00fcber den Boten dar.<br \/>\n<\/span><\/span><\/div>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3369\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">\u00a0<\/span><\/span><\/div>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3370\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">In diesem bemerkenswerten Prozess spricht die Stimme der Offenbarung erneut. Das Wort und der Ton sind in der Welt. Zum ersten Mal in der Geschichte ist f\u00fcr euch und f\u00fcr die Welt die Aufzeichnung der urspr\u00fcnglichen gesprochenen Offenbarung verf\u00fcgbar, um erfahren zu werden.<br \/>\n<\/span><\/span><\/div>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3436\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">\u00a0<\/span><\/span><\/div>\n<div id=\"yui_3_16_0_ym19_1_1467955126517_3435\" dir=\"ltr\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3177\"><span id=\"yui_3_16_0_ym19_1_1467955126517_3178\">M\u00f6gest du der  Empf\u00e4nger dieses Geschenks der Offenbarung werden und m\u00f6gest du dich \u00f6ffnen, um diese einmalige Botschaft f\u00fcr dich und f\u00fcr dein Leben zu empfangen.<\/span><\/span><\/div>\n<br \/>\n<\/div><\/div><br \/>\n<\/div>\n<div id=\"tabs-2\"><br \/>\n<em> Anmerkung an den Leser:<br \/>\nDiese \u00dcbersetzung wurde der Society von einem Sch\u00fcler der Neuen Botschaft verf\u00fcgbar gemacht, der den englischen Originaltext als Freiwilliger \u00fcbersetzt hat. Wir stellen diese \u00dcbersetzung in dieser fr\u00fchen Form zur Verf\u00fcgung, damit jeder Gelegenheit hat, sich mit einem Teil der Neuen Botschaft in seiner eigenen Sprache zu befassen.<\/em><br \/>\n<\/div>\n\t\t\t\t<div align=\"right\">\n\t\t\t<div class=\"fb-like\" data-href=\"\" data-layout=\"button_count\" data-action=\"like\" data-show-faces=\"false\" data-share=\"false\"><\/div>\n\t\t\t<div class=\"fb-share-button\" data-layout=\"button_count\"> <\/div>\n\t\t\t<div class=\"fb_iframe_widget\"><a href=\"https:\/\/twitter.com\/godsnewmessage?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-show-count=\"false\">Follow @godsnewmessage<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n\t\t\t<\/div> <\/div> \n\n<p>Um das Herz Gottes zu verstehen, musst du verstehen, wie Gott in der Welt wirkt und wie Gott jene betrachtet, die in Trennung leben und von Trennung begrenzt sind, indem sie in der physischen Realit\u00e4t leben. Denn ein Teil der Trennung ist in das physische Universum eingegangen, um die Trennung aufgrund ihrer eigenen Wahl zu erfahren.<\/p>\n<p>Hier zu leben ist jedoch eine schwierige Situation. Es f\u00fchrt die Menschen in Verwirrung, wobei sie ihre Uralte Heimat und ihre Quelle vergessen sowie jene, die \u00fcber sie wachen. Gott wei\u00df, dass das Leben in Trennung die Menschen verwirren wird. Sie werden unter die \u00dcberredung der Welt fallen. Sie werden unter die \u00dcberredung ihrer Kulturen und Gesellschaften fallen und sogar die Religion, wie sie hier auf der Erde formuliert worden ist.<\/p>\n<p>Gott wei\u00df, dass ohne die tiefere Kenntnis, die Gott in jede Person gelegt hat\u2014ein Leuchtfeuer, um ihr zu helfen, heimzukehren\u2014ohne dies, alle Arten von Verwirrung, Konflikt und \u00dcbel entstehen k\u00f6nnen. Und das war der Fall hier auf der Erde.<\/p>\n<p>Aber Gott liebt die Sch\u00f6pfung. Und die Sch\u00f6pfung liebt Gott. Und obwohl ihr in Trennung in der physischen Realit\u00e4t lebt, obwohl ihr ein getrenntes Individuum von anderen Individuen zu sein scheint, getrennt von eurer Quelle und in euch selbst getrennt von der tieferen Kenntnis, die Gott in euch gelegt hat, seid ihr dennoch Teil der Sch\u00f6pfung. Gott liebt euch noch. Und ihr liebt Gott.<\/p>\n<p>Dies k\u00f6nnt ihr nie verlieren Sogar wenn ihr das verkommenste und s\u00fcndigste Leben lebt, werdet ihr dies nie verlieren.<\/p>\n<p>Deshalb ist es die Quelle eurer Erl\u00f6sung. Gottes Liebe zu euch und eure Liebe zu Gott sind das, was euch erl\u00f6st. Die Kenntnis, die Gott in euch gelegt hat, enth\u00e4lt diese Liebe, stellt diese Verbindung her und h\u00e4lt sie f\u00fcr immer und ewig aufrecht. Sogar wenn ihr in den weitesten Weiten der Trennung lebt, sie enth\u00e4lt eure Verbindung zu Gott und zu dem Herzen Gottes, das mit eurem Herz und eurer Seele verbunden ist.<\/p>\n<p>Hierbei kann es keine Verdammung geben. Es gibt keinen Tag des Letzten Gerichts, wie die Menschen oft denken, wie es in dieser Welt gelehrt und bekr\u00e4ftigt worden ist. Es gibt keine H\u00f6lle und keine Verdammung. Aber es gibt die H\u00f6lle der Trennung und ihr lebt nun in dieser H\u00f6lle.<\/p>\n<p>Ob ihr arm oder reich seid, ihr seid von eurer Quelle getrennt. Ihr seid von jenen getrennt, die jenseits der Welt \u00fcber euch wachen, von jenseits der physischen Realit\u00e4t. Ihr seid von der Kenntnis in euch getrennt, die den Teil von euch darstellt, der Gott nie verlassen hat.<\/p>\n<p>Eure Seele treibt im Universum, treibt auf einem gro\u00dfen Ozean, verloren. Aber weil Gott Kenntnis in euch gelegt hat, wei\u00df Gott, wo ihr seid, Und wenn ihr bereit seid, ruft euch Gott, um die R\u00fcckkehr einzuleiten.<\/p>\n<p>Wenn ihr m\u00fcde seid, hier Erf\u00fcllung zu suchen, wenn ihr von euren Ambitionen und den Ambitionen der anderen entmutigt seid, wenn ihr erkannt habt, dass ihr euch hier mit dem Leben in Trennung nicht erf\u00fcllen k\u00f6nnt, wenn ihr erkennt, dass ihr das auf der Erde nicht nachmachen k\u00f6nnt, wozu ihr hierher auf die Erde gekommen seid, dann werdet ihr einen Punkt, den Wendepunkt, erreicht haben. Und langsam und allm\u00e4hlich werdet ihr mit eurer R\u00fcckkehr beginnen.<\/p>\n<p>Gott wei\u00df, dass ihr schlie\u00dflich zur\u00fcckkehren werdet, aber bis dahin schmachtet und leidet ihr und erleidet die Grausamkeiten von anderen, und eurer eigenen Schroffheit gegen euch selbst. Ihr erleidet so vieles. Ihr k\u00f6nnt dieses Leiden nicht erleichtern, au\u00dfer ihr beginnt mit eurer R\u00fcckkehr, indem ihr euch wieder mit der Kenntnis verbindet, die Gott in euch gelegt hat, welche eure Erl\u00f6sung beinhaltet.<\/p>\n<p>Die Kenntnis ist nicht hier, um euch aus der Welt zu nehmen, sondern um euch mit einem h\u00f6heren Zweck hierherzubringen. Denn Gott hat euch einen h\u00f6heren Zweck gegeben, um hier unter genau den Umst\u00e4nden in dieser Welt zu sein, die ihr in der Realit\u00e4t eurer Situation zu vermeiden oder abzulehnen neigt.<\/p>\n<p>Gott versucht, euch in eurer eigenen einmaligen Art und Weise an die Arbeit zu bringen, damit ihr eure Rolle spielt, die Trennung in euch und zwischen euch und anderen ungeschehen zu machen. Und ihr werdet diese Arbeit jenseits dieses Lebens fortsetzen. Denn wenn ihr hier weggeht, gehst du nicht in den Himmel oder in die H\u00f6lle . Ihr betretet eine andere Ebene des Dienstes und dient jenen, die zur\u00fcckgeblieben sind und unterst\u00fctzt sie, wenn ihr k\u00f6nnt, wenn ihr \u00fcber sie wacht.<\/p>\n<p>Es ist ein perfekter Plan.. Es ist Gottes Gr\u00f6\u00dferer Plan, den keine Religion in dieser Welt oder irgendeiner Welt je enthalten k\u00f6nnte. Wie k\u00f6nnte euer religi\u00f6ses Verst\u00e4ndnis ein Universum mit Billionen und Aber-Billionen von Rassen und mehr in dieser Galaxie und anderen Galaxien erfassen, die alle in Trennung leben? Und sogar die immense Ausdehnung der physischen Realit\u00e4t ist nur ein Teil von Gottes zeitloser Sch\u00f6pfung.<\/p>\n<p>Nur wenn ihr die Trennung aufhebt, wedet ihr beginnen zu verstehen, was die Trennung verursacht hat. Im Moment k\u00f6nnt ihr dies nicht verstehen. Eure Religionen k\u00f6nnen dies nicht verstehen. Die kl\u00fcgste Person in der Welt kann dies nicht verstehen, denn sie ist noch eingeschr\u00e4nkt von der Trennung. Deshalb gibt es keine Meister, die in der Welt leben, denn Meisterschaft herrscht jenseits der Welt. Obwohl es jene gibt, die weise und kompetent sind und \u00fcber Einsicht verf\u00fcgen, ist die Meisterschaft jenseits dieser Welt\u2014auf einer h\u00f6heren Ebene, jenseits des Nebels der Welt, jenseits der Wolken der Verwirrung hier, hier auf dem Boden.<\/p>\n<p>Deshalb k\u00f6nnen eure Religionen nur Ann\u00e4herungen einer gr\u00f6\u00dferen Wahrheit sein. Lebend in Zeit, Raum und Wandel k\u00f6nnt ihr nur einen Teil sehen. Deshalb hat Gott der Welt die gro\u00dfen Offenbarungen gegeben, um Zeugnisse dieser Gr\u00f6\u00dferen Realit\u00e4t zu sein. Eine gro\u00dfe Offenbarung allein kann dies nicht vollst\u00e4ndig leisten. Tats\u00e4chlich braucht ihr sie alle.<\/p>\n<p>Sie stellen Gottes gro\u00dfe Sorge um diese Welt und andere Welten dar, die im Moment weit weniger frei sind als ihr. Denn Freiheit ist selten im Universum. Sie ist so schwer unter den Nationen der Getrennten zu erreichen. Aber sie kann erreicht werden, und wenn dies geschehen ist, ist es ein gro\u00dfes Geschenk nicht nur f\u00fcr jene Welt und jene V\u00f6lker, sondern f\u00fcr das ganze Universum.<\/p>\n<p>Was Wir euch heute hier sagen, stellt das Herz Gottes dar. Denn es gibt nichts B\u00f6ses in Gott. Es gibt keine Rache in Gott. Es gibt keine Grausamkeit oder Bestrafung in Gott. Daher k\u00f6nnt ihr nicht Religion als Kriegsbanner oder als Rechtssystem verwenden, um andere zu bestrafen, andere zu foltern oder andere zu exekutieren. Das ist ein Verbrechen gegen Gott und Gottes Willen und Zweck f\u00fcr die Welt. Jede Schrift oder Interpretation, die diese Dinge bef\u00fcrwortet, ist unecht und missverstanden.<\/p>\n<p>Warum sollte Gott euch bestrafen, wenn ihr ohne Kenntnis seid, wenn Gott wei\u00df, dass ohne Kenntnis, die Gott in euch gelegt hat, um euch zu f\u00fchren, ihr Fehler und Konflikt zum Opfer fallen und grausam gegen euch und andere sein w\u00fcrdet? Warum sollte Gott euch bestrafen, wenn ihr t\u00f6richt und ignorant seid? Gott vergibt euch, weil ihr nicht wisst, was ihr tut.<\/p>\n<p>Bis Kenntnis euch f\u00fchren kann\u2014die Kenntnis, die Gott in jede Person gelegt hat, religi\u00f6s oder nicht, in jeder Kultur und Nation\u2014bis ihr dem folgen k\u00f6nnt, wisst ihr nicht, was ihr tut. Ihr kennt nicht euren Zweck. Ihr kennt nicht eure Bestimmung. Ihr wisst nicht, wer euch hierher gesandt hat und zu welchem Zweck. Ihr seid verloren, treibt dahin, seid euch selbst \u00fcberlassen, erschlafft im Laufe der Zeit, versucht, gl\u00fccklich zu sein, versucht, Schmerz zu vermeiden, werdet korrupt in einer korrupten Welt, voll von Korruption.<\/p>\n<p>Gott wei\u00df, dass ihr ohne die Segnungen der Sch\u00f6pfung alle Wohltaten der Sch\u00f6pfung verlieren w\u00fcrdet. Gott wei\u00df, dass ihr getrennt von eurer Uralten Heimat alle Wohltaten eurer Uralten Heimat verlieren w\u00fcrdet.<\/p>\n<p>H\u00f6lle und Verdammung sind eine menschliche Erfindung, um die Menschen in den Glauben zu pferchen, sie zu bedrohen. Aber die Trag\u00f6die ist, wenn ihr Gottes Offenbarungen nicht empfangt, die eine, die f\u00fcr euch bestimmt ist und nicht lernt, sie zu verstehen, ihr dann in Trennung ermattet und nicht in der Lage sein werdet, ihr zu entkommen.<\/p>\n<p>Es ist, als ob ihr in eine tiefe Schlucht, einen Canyon hinabgestiegen seid und Gott Leitern gesandt hat, um euch zu helfen, herauszuklettern. Aber wenn ihr nicht herausklettert, steckt ihr dort unten fest. Ihr k\u00f6nnt euch nicht selbst herausw\u00fcnschen. Gott wird euch nicht eines Tages einfach erh\u00f6hen und alle eure Fehler ausradieren. Und Glaube wird euch nicht herausbringen, da Glaube nicht wahr ist, es sei denn, ihr werdet von Kenntnis gef\u00fchrt.<\/p>\n<p>Ihr k\u00f6nnt nicht euren Weg aus dieser Situation herausglauben. Ihr m\u00fcsst lernen, auf der anderen Seite unter Verwendung der Leitern, die Gott herabgelassen hat, hochzuklettern. Und Gott hat mehr als eine Leiter herabgelassen, denn Gott wei\u00df, dass nicht jeder nur einer Leiter folgt. Gott wei\u00df, dass nicht jeder nur einer Lehre und einem Lehrer folgt. Und Gott wei\u00df, dass jede gro\u00dfe Offenbarung, die in die Welt gebracht wurde, von den Menschen im Laufe der Zeit verdorben wird und dass es daher weitere Offenbarungen geben muss, um Kl\u00e4rung und Korrektur aller Fehler zu bringen, die die Menschheit bei den fr\u00fcheren Offenbarungen gemacht hat.<\/p>\n<p>Es ist die Liebe Gottes und die Sorge Gottes um euch und um alle, die hier leben, was den Anlass zu diesem gro\u00dfen Angebot der Erl\u00f6sung gegeben hat.<\/p>\n<p>Gott hat einen perfekten Plan. Keine Religion kann darauf Anspruch des Eigentums erheben, aber jede Religion kann sich ihm n\u00e4hern und euch die richtige Richtung anzeigen, wenn dies frei von Verurteilung geschieht, frei von Fehlern der Menschheit, die t\u00f6richterweise annimmt, dass sie Gottes Willen kennt und wei\u00df, wie Gott in der Welt wirkt.<\/p>\n<p>Die Menschen denken, sie verst\u00fcnden das Mysterium, aber sie haben noch nicht einmal begonnen, das Mysterium zu verstehen. Das Mysterium ist, was jenseits eures intellektuellen Verst\u00e4ndnisses existiert. Der Weg zu Gott ist jenseits eures intellektuellen Verst\u00e4ndnisses. Ihr m\u00fcsst bereit sein, jenseits zu gehen, wenn ihr eure R\u00fcckkehr fortsetzen wollt.<\/p>\n<p>Jene, die religi\u00f6se Fundamentalisten werden, sind in K\u00e4figen seitlich des Berges eingesperrt. Sie k\u00f6nnen nicht aufsteigen. Sie haben rund um sich eine Mauer gebaut, die sie weiter von jenen trennt, die sie umgeben und vertiefen dadurch ihre Trennung. Sogar wenn sie f\u00fcr ihre religi\u00f6sen Prinzipien eintreten, vertiefen sie ihre Trennung, sie entfernen sich immer weiter vom Willen und vom Zweck Gottes in der Welt. Das ist der Grund, weshalb religi\u00f6se Figuren dazu tendieren werden, gegen eine Neue Offenbarung in der Welt Widerstand zu leisten. Sie bedroht ihren Glauben, das Fundament, auf das sie sich st\u00fctzen. Es fordert sie heraus, \u00fcber ihre Vorstellungen und ihre Ideologie hinauszugehen, da dies alles etwas vom Verstand ist und nicht vom Herzen und von der Seele. Die Seele kehrt ohne Annahme, ohne Ermahnung, ohne Verurteilung zu Gott zur\u00fcck.<\/p>\n<p>Also hat Gott alle Weltreligionen initiiert, von denen jede ein kritischer Baustein der menschlichen Zivilisation nach einem h\u00f6heren ethischen Prinzip ist, was die Macht der Kenntnis in der Welt am Leben erh\u00e4lt, w\u00e4hrend sie in anderen Welten im Universum ausgestorben ist oder nie gehegt wurde.<\/p>\n<p>Alle Religionen sind wichtig. Sie gleichen einander aus\u2014die Exzesse und den Extremismus. Sie korrigieren die Fehler der Vergangenheit. Sie verfeinern den Ansatz, da Gott wei\u00df, dass nicht jeder einem Weg oder einem Lehrer folgen kann, sogar die gro\u00dfen Boten.<\/p>\n<p>So treffen die Fl\u00fcsse, die alle in dasselbe Meer flie\u00dfen, zusammen und vereinen sich auf einer h\u00f6heren Ebene. Und obwohl sich ihre Ideologie unterscheiden mag und sie im Gegensatz zueinander sind, dienen alle einem h\u00f6heren Zweck.<\/p>\n<p>Denn eure R\u00fcckkehr zu Gott ist kein intellektuelles Unterfangen Sie baut nicht auf einen Berg des Glaubens und der Annahme auf. Denn wahrer Glaube wird euch zum Mysterium f\u00fchren. Und das Mysterium wird euch jenseits des Glaubens f\u00fchren, denn Gott und die Sch\u00f6pfung existieren jenseits des menschlichen Verst\u00e4ndnisses oder des Verst\u00e4ndnisses irgendeiner Rasse im Universum. Denn wer kann annehmen, den Gott aller Sch\u00f6pfung zu kennen, von unz\u00e4hligen Welten wie eurer, von unz\u00e4hligen Rassen, die so verschieden von der Menschheit sind?<\/p>\n<p>Denn das erste Mal in der Geschichte \u00f6ffnet Gott die T\u00fcren zum Leben im Universum. Denn um zu verstehen, was Gott in dieser Welt tut, m\u00fcsst ihr verstehen, was Gott im gesamten Universum tut.<\/p>\n<p>Es war nie vorher m\u00f6glich, diese Dinge zu pr\u00e4sentieren, denn die Menschheit ist noch in einem sehr primitiven Zustand. Aber nun steht die Menschheit an der Schwelle zum Weltraum und die Intervention von Rassen jenseits der Welt hat bereits begonnen\u2014eine gef\u00e4hrliche Intervention, eine geheime Intervention. Also muss die Menschheit nun von diesen Dingen erfahren und nur Gottes Neue Offenbarung kann euch darauf vorbereiten.<\/p>\n<p>Ebenso hat die Menschheit die Welt so ausreichend ver\u00e4ndert, dass sie sich nun selbst ver\u00e4ndern wird, eine neue Welterfahrung gro\u00dfer Schwierigkeit und Gefahr f\u00fcr die menschliche Familie, eine \u00c4nderung auf einem Niveau, wie es nie vorher in der Welt zu sehen war. Daher hat Gott erneut gesprochen, um euch darauf vorzubereiten.<\/p>\n<p>Die Weltreligionen streiten untereinander und sind innerlich zerrissen. Und religi\u00f6ser Fundamentalismus und religi\u00f6se Gewalt erheben sich hier und da mit gro\u00dfer Zerst\u00f6rung und weiterer Teilung der menschlichen Familie, weiterem Bruch der menschlichen Familie, weiterer Schw\u00e4chung der menschlichen Familie zu einer Zeit, wenn menschliche Zusammenarbeit und Einheit lebenswichtig f\u00fcr eure Zukunft in einer Welt des Verfalls sind.<\/p>\n<p>Das Herz Gottes wei\u00df dies und hat eine Neue Offenbarung gesandt, um Kl\u00e4rung zu bringen, um euer Verst\u00e4ndnis des Zwecks aller Weltreligion wiederherzustellen und welche Rolle jede von ihnen spielen, um die Menschheit zu einen und vorzubereiten auf die Gro\u00dfen Wellen des Wandels, die auf diese Welt zukommen und auf ihre Begegnung mit einem Universum voller intelligenten Lebens\u2014die zwei gr\u00f6\u00dften  Ereignisse in der ganzen menschlichen Geschichte.<\/p>\n<p>Die Weltreligionen m\u00fcssen nun Teil der L\u00f6sung sein und nicht Teil des Problems, denn sie sind alle dazu gedacht, die Menschheit zu einen und ein gro\u00dfer Schatz f\u00fcr die Menschheit zu sein. Aber dies erfordert gro\u00dfe Kl\u00e4rung und Wiederherstellung ihres urspr\u00fcnglichen Zwecks und ihrer Bedeutung und was sich der Himmel nun f\u00fcr sie w\u00fcnscht, was nun von der Neuen Offenbarung von Gott gestellt wird, denn Gott wei\u00df, dass die Menschheit ohne die Neue Offenbarung weiter k\u00e4mpfen wird und w\u00e4hrend die Ressourcen der Welt weniger werden und w\u00e4hrend die Bev\u00f6lkerung w\u00e4chst, ihr vor der Erwartung endlosen Kriegs und Zerst\u00f6rung steht.<\/p>\n<p>Gott wei\u00df dies nat\u00fcrlich und versucht, die Menschheit vor einem Zustand zu retten, den sie selbst f\u00fcr sich geschaffen hat, einem Zustand, den viele Rassen im Universum geschaffen haben, der h\u00e4ufig zu einer gro\u00dfen Trag\u00f6die f\u00fchrt.<\/p>\n<p>Es ist, weil Gott euch liebt und ihr Gott liebt, dass diese gro\u00dfe Offenbarung gegeben worden ist. Es ist aus diesem Grund, dass die vergangenen Offenbarungen gegeben worden sind, und dies vielleicht in einem Jahrtausend nur einmal, gegeben f\u00fcr den Moment und f\u00fcr die kommenden Zeiten, und um die Menschheit auf eine Zukunft vorzubereiten, die sie nicht vorhersehen kann\u2014so gro\u00df ist das Geschenk jeder Offenbarung.<\/p>\n<p>Ihr wisst nichts von diesen Dingen, noch nicht. Aber euer Verst\u00e4ndnis muss wachsen. Ihr m\u00fcsst \u00fcber Trennung und Diskriminierung und Unterdr\u00fcckung anderer hinauswachsen. Ihr m\u00fcsst \u00fcber die Trennungen der Religion hinauswachsen, um den Zweck der Religion zu verstehen und den Willen des Himmels in Bezug auf Religion.<\/p>\n<p>Gott wei\u00df, wie er euch erl\u00f6st, einen und alle. Warum nehmt ihr an, dass ihr wisst, was euch erl\u00f6st? Eure \u00dcberzeugungen k\u00f6nnen euch nur in die richtige Richtung lenken. Dar\u00fcber hinaus ist es die Macht der Gnade und der mysteri\u00f6se Kontakt mit der Kenntnis in euch und der zweckgerichtete Kontakt mit der Welt, der euch wieder in die richtige Richtung bringen wird und wozu ihr hier seid, um einer Welt wachsender Not  und Verzweiflung als einmaliges Geschenk zu geben.<\/p>\n<p>Ihr seid hier, um zu geben und zu dienen, nicht zu kritisieren und zu verurteilen.  Ihr seid hier, um zu vergeben und Br\u00fccken untereinander zu bauen, nicht sie niederzubrennen und endlose K\u00e4mpfe \u00fcber eure Vorstellungen, eure Sorgen, eure Gier und eure Furcht zu f\u00fchren.<\/p>\n<p>Es ist nur eine Menschheit, die zwischen ihren Nationen und Religionen kooperieren kann, die in der Lage sein wird, euch auf eine Welt des Verfalls vorzubereiten und euch die Kraft und die Wirksamkeit im Universum zu geben, wo ihr auf vereinte Welten sto\u00dfen werdet.<\/p>\n<p>Die menschliche Einheit ist nicht nur eine gute Idee. Sie ist nicht nur ein hohes moralisches Prinzip. Sie ist die Voraussetzung f\u00fcr das \u00dcberleben im Universum, wenn ihr eine freie und selbstbestimmte Rasse sein wollt, die nun mit M\u00e4chten streitet, die nicht frei sind.<\/p>\n<p>Ihr k\u00f6nnt dies tun, aber es muss eine gro\u00dfe \u00c4nderung des Verst\u00e4ndnisses geben, eine gro\u00dfe Abrechnung, eine gro\u00dfe Konfrontation mit der Wirklichkeit. Eine Neue Offenbarung von Gott ist erforderlich, um die Weltreligionen in eine gro\u00dfe Einheit und Zusammenarbeit zu bringen, um euer Verst\u00e4ndnis von Gottes Willen und des Zwecks f\u00fcr die Welt zu kl\u00e4ren und wie Gott hier wirkt, durch Individuen von innen heraus wirkt.<\/p>\n<p>Sie wird zu einer Zeit gro\u00dfer und wachsender Krise in der Welt gegeben, gr\u00f6\u00dfer als ihr jetzt versteht. Das Bed\u00fcrfnis ist so gro\u00df. Und Gottes Liebe hat eine gro\u00dfe Offenbarung hierher zu euch und zu anderen gebracht. Obwohl nicht jeder in der Lage sein wird, sie zu empfangen und anzunehmen, m\u00fcssen genug Menschen es tun, um den Verlauf menschlichen Verhaltens und Verst\u00e4ndnisses zu \u00e4ndern.<\/p>\n<p>Ihr k\u00f6nnt dies tun, denn ihr liebt Gott und Gott liebt euch. Und das Band zwischen euch ist nie vollst\u00e4ndig gerissen. Sogar, obwohl ihr gew\u00e4hlt habt, in Trennung zu kommen und euch hier aufzuhalten, ist die Bindung noch lebendig und m\u00e4chtig in euch. Sie ersetzt eure religi\u00f6sen \u00dcberzeugungen. Sie ist wichtiger als eure Vorstellungen. Sie ist m\u00e4chtiger als irgendetwas, was ihr f\u00fcr m\u00e4chtig haltet.<\/p>\n<p>Sie kann euch erl\u00f6sen. Sie kann euer Leben \u00e4ndern. Sie kann die Bindungen zu anderen erneuern. Sie kann Br\u00fccken zwischen Nationen bauen, nun aus Notwendigkeit gebaut, denn die Menschheit muss sich vereinen, um in einer Welt des Verfalls zu \u00fcberleben.<br \/>\nDie Religionen werden fortgesetzt, denn sie sind alle wichtig. Versucht nicht, eure eigene Religion zu machen, denn das ist t\u00f6richt. Denn Gott hat die Leitern herabgelassen in die tiefe Schlucht, mehr als eine, damit jeder die Chance hat, herauszuklettern. Aber nun hat Gott eine weitere Leiter in die Schlucht herabgelassen, denn dies ist zu dieser Zeit notwendig, zu einer Zeit der Offenbarung.<\/p>\n<p>Ein Bote wurde vom Engelsrat in die Welt gesandt, von dem alle Boten gekommen sind. Es kann also keinen wirklichen Streit zwischen den Weltreligionen geben, denn jene, die kamen, um sie zu bringen, kamen alle von derselben Quelle. Halb heilig, halb menschlich sind sie, wenn sie einmal in der Welt sind. Sie sind keine G\u00f6tter. Denn es gibt keinen Gott au\u00dfer Gott. Aber sie sind die wichtigsten Menschen in der Welt, denn sie sind gekommen, um zu geben und aufgrund des gro\u00dfen Wandels und der Wohltat, die sie bieten k\u00f6nnen, f\u00fcr diese Zeit und f\u00fcr die kommenden Zeiten.<\/p>\n<p>Dies ist eure Herausforderung. Ihr braucht einen Wandel des Herzens, um eine gr\u00f6\u00dfere Rolle in der Welt zu spielen. Ihr m\u00fcsst die Offenbarung empfangen, um euren eigenen religi\u00f6sen Weg zu verstehen.<\/p>\n<p>Lasst Gott euch nun helfen. Lasst Gott die Welt unterst\u00fctzen. Gott wird die Welt nicht \u00fcbernehmen. Aber Gott wird euch m\u00e4chtig genug machen und vereint genug, um die Welt wiederherzustellen und eine Zukunft zu schaffen, die weit besser als die Vergangenheit ist, um die menschliche Freiheit und Souver\u00e4nit\u00e4t im Universum zu bewahren, und um der Welt eine dauerhafte Heimat hier in der Welt zu geben, f\u00fchrend zu gr\u00f6\u00dferen Leistungen und Erf\u00fcllung und um die Gefahren einer Katastrophe zu vermeiden<\/p>\n<p>Es ist aufgrund des Herzens Gottes, das euch nun gegeben wird, dass Wir nun zu euch sprechen und dass der Bote nun hier ist. Versteht dies und euer Leben wird in den Fokus kommen. Und euer Herz wird wachsen. Eure Kraft wird wachsen. Und die Liebe in euch wird in die Welt freigesetzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um das Herz Gottes zu verstehen, musst du verstehen, wie Gott in der Welt wirkt und wie Gott jene betrachtet, die in Trennung leben und von Trennung begrenzt sind, indem sie in der physischen Realit\u00e4t leben. Denn ein Teil der Trennung ist in das physische Universum eingegangen, um die Trennung aufgrund ihrer eigenen Wahl zu\u2026 <a class=\"read-more\" href=\"https:\/\/www.v6.newmessage.org\/de\/about-recording-shortcode\/\"><span>Read More<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"parent":16297,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-leftsidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[76,118,30,379,460],"tags":[665,666,640],"_links":{"self":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/27200"}],"collection":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/comments?post=27200"}],"version-history":[{"count":5,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/27200\/revisions"}],"predecessor-version":[{"id":28748,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/27200\/revisions\/28748"}],"up":[{"embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/pages\/16297"}],"wp:attachment":[{"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/media?parent=27200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/categories?post=27200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.v6.newmessage.org\/de\/wp-json\/wp\/v2\/tags?post=27200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}